{"id":805,"date":"2020-12-24T02:19:24","date_gmt":"2020-12-24T07:19:24","guid":{"rendered":"https:\/\/sorinionescu.org\/non-classifiee\/sur-le-declin-et-lechec-des-medias-dialogue-avec-roberto-savio\/"},"modified":"2020-12-24T03:02:01","modified_gmt":"2020-12-24T08:02:01","slug":"sur-le-declin-et-lechec-des-medias-dialogue-avec-roberto-savio","status":"publish","type":"post","link":"https:\/\/sorinionescu.org\/fr\/articles-fr\/sur-le-declin-et-lechec-des-medias-dialogue-avec-roberto-savio\/","title":{"rendered":"Sur le d\u00e9clin et l&rsquo;\u00e9chec des m\u00e9dias &#8211; dialogue avec Roberto Savio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"805\" class=\"elementor elementor-805 elementor-795\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d9ed91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d9ed91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7ef386\" data-id=\"c7ef386\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-180c6da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"180c6da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7067695\" data-id=\"7067695\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16be008 elementor-widget elementor-widget-image\" data-id=\"16be008\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\" class=\"attachment-large size-large wp-image-797\" alt=\"\" srcset=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png 640w, https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance.-300x199.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-809b13d\" data-id=\"809b13d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f322f elementor-widget elementor-widget-text-editor\" data-id=\"68f322f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Roberto_Savio\">Roberto Savio<\/a> est journaliste, expert en communication, commentateur politique, militant pour la justice sociale et climatique et militant pour la gouvernance mondiale. Il est le fondateur et pr\u00e9sident \u00e9m\u00e9rite de l&rsquo;agence de presse <a href=\"http:\/\/www.ips.org\/\">Inter Press Service (IPS)<\/a> et \u00e9diteur de <a href=\"https:\/\/www.other-news.info\/\">Other News<\/a>.<\/p>\n<p>J&rsquo;ai eu la chance de rencontrer Roberto gr\u00e2ce \u00e0 mon militantisme, et lorsque j&rsquo;ai commenc\u00e9 \u00e0 m&rsquo;int\u00e9resser \u00e0 la construction du sens et au r\u00f4le que l&rsquo;\u00e9chec et le d\u00e9clin des m\u00e9dias y ont jou\u00e9, je lui ai demand\u00e9 d&rsquo;engager un dialogue sur le sujet. Son expertise et sa sagesse dans ce domaine sont vastes, et je lui suis tr\u00e8s reconnaissant du temps qu&rsquo;il m&rsquo;a accord\u00e9 et du dialogue qui a suivi.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-67aebaa elementor-widget elementor-widget-heading\" data-id=\"67aebaa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Summary<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f32069d elementor-widget elementor-widget-text-editor\" data-id=\"f32069d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roberto commence par d\u00e9crire trois points critiques du d\u00e9clin des m\u00e9dias qui ont interagi les uns avec les autres, tous li\u00e9s \u00e0 la transition de l&rsquo;\u00e8re <strong>Gutenberg<\/strong> \u00e0 l&rsquo;\u00e8re <strong>Zuckerberg<\/strong>.<\/p>\n<ol>\n<li>Les revenus publicitaires, qui constituaient la majeure partie des revenus de nombreuses agences de presse (80 %), ont diminu\u00e9 r\u00e9guli\u00e8rement, les annonces passant des m\u00e9dias d&rsquo;information aux soci\u00e9t\u00e9s Internet telles que Google et Facebook.<\/li>\n<li>Pour compenser la perte de stabilit\u00e9 financi\u00e8re, les agences de presse sont devenues beaucoup plus orient\u00e9es vers le march\u00e9 qu&rsquo;auparavant, vendant des histoires glamour qui pouvaient \u00eatre \u00e9crites rapidement au lieu de pi\u00e8ces analytiques complexes, longues et co\u00fbteuses.<\/li>\n<li>L&rsquo;augmentation des m\u00e9dias sociaux a \u00e9galement contribu\u00e9 \u00e0 une r\u00e9duction significative de la dur\u00e9e d&rsquo;attention des gens, les jeunes ayant une dur\u00e9e d&rsquo;attention de 7 secondes. Il est impossible d&rsquo;\u00e9crire un journal avec des articles qui peuvent \u00eatre lus en 7 secondes, sauf s&rsquo;il s&rsquo;agit d&rsquo;un journal \u00e0 gros titres.<\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ce411 elementor-blockquote--skin-quotation elementor-blockquote--align-left elementor-blockquote--button-view-icon elementor-blockquote--button-skin-bubble elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"30ce411\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t<p>Le vrai journalisme consiste \u00e0 pouvoir analyser, rassembler toutes les donn\u00e9es, de sorte que votre lecteur dispose de nombreux \u00e9l\u00e9ments sur lesquels il peut s'appuyer pour comprendre. Aujourd'hui, le march\u00e9 a r\u00e9duit ce type de journalisme parce que ce type de journalisme co\u00fbte de l'argent et du temps. Si vous envoyez un journaliste au Y\u00e9men avec un t\u00e9l\u00e9porteur, au maximum apr\u00e8s deux ou trois jours, il doit commencer \u00e0 envoyer des articles. Maintenant, pour aller au Y\u00e9men et pour comprendre la situation, il vous faudra au moins une semaine. Le journalisme devient donc de plus en plus superficiel car le march\u00e9 ne r\u00e9compense pas les journalistes simplement parce que l'argent est ailleurs. Donc, si vous \u00eates r\u00e9dacteur en chef, \u00e9diteur d'un journal, et que vous devez survivre, vous devez faire des choix. Et quel choix ferez-vous ? Je vendrai ce qui est le plus simple, pas ce qui est le plus complexe. Je vendrai ce qui est plus familier, pas quelque chose pour lequel je dois faire beaucoup d'explications pour situer le lecteur.<\/p>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Roberto Savio<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/intent\/tweet?text=%3Cp%3ELe+vrai+journalisme+consiste+%C3%A0+pouvoir+analyser%2C+rassembler+toutes+les+donn%C3%A9es%2C+de+sorte+que+votre+lecteur+dispose+de+nombreux+%C3%A9l%C3%A9ments+sur+lesquels+il+peut+s%27appuyer+pour+comprendre.+Aujourd%27hui%2C+le+march%C3%A9+a+r%C3%A9duit+ce+type+de+journalisme+parce+que+ce+type+de+journalisme+co%C3%BBte+de+l%27argent+et+du+temps.+Si+vous+envoyez+un+journaliste+au+Y%C3%A9men+avec+un+t%C3%A9l%C3%A9porteur%2C+au+maximum+apr%C3%A8s+deux+ou+trois+jours%2C+il+doit+commencer+%C3%A0+envoyer+des+articles.+Maintenant%2C+pour+aller+au+Y%C3%A9men+et+pour+comprendre+la+situation%2C+il+vous+faudra+au+moins+une+semaine.+Le+journalisme+devient+donc+de+plus+en+plus+superficiel+car+le+march%C3%A9+ne+r%C3%A9compense+pas+les+journalistes+simplement+parce+que+l%27argent+est+ailleurs.+Donc%2C+si+vous+%C3%AAtes+r%C3%A9dacteur+en+chef%2C+%C3%A9diteur+d%27un+journal%2C+et+que+vous+devez+survivre%2C+vous+devez+faire+des+choix.+Et+quel+choix+ferez-vous+%3F+Je+vendrai+ce+qui+est+le+plus+simple%2C+pas+ce+qui+est+le+plus+complexe.+Je+vendrai+ce+qui+est+plus+familier%2C+pas+quelque+chose+pour+lequel+je+dois+faire+beaucoup+d%27explications+pour+situer+le+lecteur.%3C%2Fp%3E%0A+%E2%80%94+Roberto+Savio&amp;url=https%3A%2F%2Fsorinionescu.org%2Ffr%2F%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F805\" class=\"elementor-blockquote__tweet-button\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tweet<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f1b49 elementor-widget elementor-widget-video\" data-id=\"f3f1b49\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/VdUrK2RLNoA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eda1bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eda1bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0d20d7\" data-id=\"a0d20d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa0166e elementor-widget elementor-widget-heading\" data-id=\"fa0166e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transcription int\u00e9grale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa73192 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa73192\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-352348f\" data-id=\"352348f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea253ee elementor-widget elementor-widget-text-editor\" data-id=\"ea253ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&nbsp;<\/p>\n<p><i><span style=\"font-weight: 400;\">Quel est l&rsquo;\u00e9tat des m\u00e9dias \u00e0 l&rsquo;heure actuelle et pourquoi en est-il ainsi ? Que s&rsquo;est-il pass\u00e9 ?\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Cela pourrait \u00eatre pertinent par rapport \u00e0 ce que vous avez dit, vous venez de me dire que nous ne sommes pas \u00e0 l&rsquo;\u00e8re Gutenberg, nous sommes \u00e0 l&rsquo;\u00e8re Zuckerberg, d&rsquo;o\u00f9 je d\u00e9duis que les m\u00e9dias sociaux ont quelque chose \u00e0 voir avec cela, mais pouvez-vous nous en dire un peu plus ?\u00a0\u00a0\u00a0\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Eh bien regardez, mon point de vue est tr\u00e8s simple. Lorsque nous \u00e9tions \u00e0 l&rsquo;\u00e8re de l&rsquo;information, l&rsquo;information \u00e9tait l&rsquo;outil central pour la soci\u00e9t\u00e9, pour les individus, pour la connaissance, pour la science. Il y avait de l&rsquo;information et cela signifiait que l&rsquo;information avait une valeur marchande. De sorte que si vous imprimiez le journal, vous gagniez de l&rsquo;argent &#8211; aussi parce que la publicit\u00e9 repr\u00e9sentait pr\u00e8s de quatre-vingt pour cent du budget de tout journal, des revenus du journal, et que seuls les m\u00e9dias devaient y aller. Les m\u00e9dias \u00e9taient donc puissants, ils faisaient de l&rsquo;argent et \u00e9taient tr\u00e8s professionnels en g\u00e9n\u00e9ral. Il y avait l&rsquo;id\u00e9e que les m\u00e9dias devaient \u00eatre comp\u00e9titifs en termes de qualit\u00e9. M\u00eame si vous \u00e9tiez un journal local, vous consid\u00e9rez toujours les grands journaux comme un paradigme du journalisme, du style r\u00e9dactionnel et de la responsabilit\u00e9 envers les lecteurs, etc. Ce qui s&rsquo;est pass\u00e9 depuis l&rsquo;arriv\u00e9e de l&rsquo;\u00e8re Zuckerberg, c&rsquo;est que l&rsquo;information n&rsquo;est plus l&rsquo;outil permettant \u00e0 la soci\u00e9t\u00e9 d&rsquo;avoir une fen\u00eatre sur le monde. L&rsquo;information \u00e9tait la fen\u00eatre sur le monde, sur votre ville, sur votre pays, sur votre r\u00e9gion et sur le monde. L&rsquo;individu \u00e9tait capable de lire tout cela et d&rsquo;en tirer ses conclusions. Bien s\u00fbr, les m\u00e9dias ont fait preuve de partialit\u00e9. Il y avait des journaux de droite, des journaux de gauche, des journaux d&rsquo;\u00e9lite, des journaux populaires, mais dans l&rsquo;ensemble, il y avait un horizon qui offrait au citoyen une vue du monde.\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La radio qui est arriv\u00e9e, et la t\u00e9l\u00e9vision plus tard, n&rsquo;ont pas beaucoup chang\u00e9 ce syst\u00e8me car c&rsquo;\u00e9tait aussi un syst\u00e8me d&rsquo;information, et on pouvait discuter si les images visuelles \u00e9taient plus puissantes que les mots \u00e9crits. C&rsquo;\u00e9tait le probl\u00e8me de savoir quel m\u00e9dia vous utiliseriez. Les m\u00e9dias \u00e9taient tous des instruments pour atteindre les gens. Vous pouviez utiliser la radio, la t\u00e9l\u00e9vision, les journaux, tout ce que vous vouliez.\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Avec l&rsquo;arriv\u00e9e de l&rsquo;\u00e8re Zuckerberg, trois choses se sont produites. La premi\u00e8re : toutes les publicit\u00e9s sont all\u00e9es sur Internet, sur Google, etc. En fait, ils gagnent leur argent en nous vendant comme un produit. C&rsquo;est ainsi que ces entreprises gagnent de l&rsquo;argent. Elles sont gratuites, il n&rsquo;y a pas d&rsquo;abonnement, et elles gagnent de l&rsquo;argent en utilisant les gens, leurs clients, pour tout, de la politique au marketing. Cela a entra\u00een\u00e9 une tr\u00e8s tr\u00e8s lourde perte pour le syst\u00e8me d&rsquo;information et c&rsquo;est quelque chose qui ne devrait jamais \u00eatre sous-\u00e9valu\u00e9, car cette perte de force financi\u00e8re pour les m\u00e9dias a eu une deuxi\u00e8me cons\u00e9quence. Pour \u00eatre comp\u00e9titif, pour rester sur le march\u00e9, l&rsquo;information est devenue de plus en plus une valeur marchande et orient\u00e9e vers le march\u00e9, l&rsquo;information \u00e9tant laiss\u00e9e par un grand processus pour se concentrer sur les \u00e9v\u00e9nements et donnant de plus en plus le privil\u00e8ge aux personnes connues (c\u00e9l\u00e9brit\u00e9s) et non aux inconnus.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela signifie que le nombre de s\u00e9lections qui \u00e9taient en fait des s\u00e9lections de marketing, et l&rsquo;information est devenue beaucoup plus orient\u00e9e vers le march\u00e9 et d\u00e9pendante du march\u00e9 qu&rsquo;auparavant. Le troisi\u00e8me ph\u00e9nom\u00e8ne est le fait que, professionnellement, cette profession a lentement, je ne veux pas dire dispara\u00eetre, mais il est certain que cette profession ne durera pas longtemps. Lorsque l&rsquo;intelligence artificielle arrivera, vous verrez que l&rsquo;intelligence artificielle peut faire bon nombre des t\u00e2ches qu&rsquo;un journaliste fait aujourd&rsquo;hui, et le journalisme dispara\u00eetra tel que nous le connaissons aujourd&rsquo;hui. Il subsistera dans quelques rares m\u00e9dias, mais ils dispara\u00eetront, devront passer au num\u00e9rique. Si vous parvenez \u00e0 rester imprim\u00e9, seuls deux types de journaux verront le jour : les tr\u00e8s tr\u00e8s bons que l&rsquo;\u00e9lite doit lire pour savoir ce qui se passe, mais il pourrait y en avoir deux, trois, au Canada peut-\u00eatre deux, pas plus, et ensuite le journal local qui sera m\u00eame gratuit, dans lequel vous trouverez les pharmacies ouvertes, ce qui n&rsquo;est pas un film de votre ville, des informations qui ont trait \u00e0 votre vie locale, mais ils abandonneront compl\u00e8tement tout potentiel de couverture mondiale de la vision internationale, voire de la vision nationale.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le march\u00e9 est donc en train de changer cela, le deuxi\u00e8me point, mais le deuxi\u00e8me point am\u00e8ne au troisi\u00e8me point. L&rsquo;arriv\u00e9e de l&rsquo;internet a \u00e9galement cr\u00e9\u00e9 une diff\u00e9rence g\u00e9n\u00e9rationnelle. Les jeunes n&rsquo;ach\u00e8tent plus de journaux parce qu&rsquo;ils ne sont plus capables de les lire en long. Il y a beaucoup de d\u00e9filement. Selon Microsoft, la dur\u00e9e essentielle d&rsquo;un adolescent aujourd&rsquo;hui est de sept secondes ! C&rsquo;est exactement le contraire de ce dont vous avez besoin pour lire un journal, \u00e0 moins que vous ne fassiez un journal avec des titres de 150 caract\u00e8res, comme twitter, parce que vous ne pouvez pas demander aux jeunes d&rsquo;avoir plus d&rsquo;attention que cela. Nous parlons en termes g\u00e9n\u00e9raux, nous ne parlons pas de tous les jeunes, nous parlons de la majorit\u00e9 des jeunes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le r\u00e9sultat est que cet autre monde qui est apparu, qui est un monde de communication dans lequel tout le monde est \u00e9gal &#8211; vous pouvez \u00eatre le plus brillant des scientifiques mais dans ce que vous \u00e9crivez sur le r\u00e9seau social, il n&rsquo;a pas beaucoup plus de pouvoir que quelqu&rsquo;un qui a th\u00e9oris\u00e9 sur un fantasme de conspiration. Au contraire, le type qui \u00e9labore un fantasme de conspiration a beaucoup plus de chances d&rsquo;avoir des lecteurs que les scientifiques. Et les moteurs de recherche des trois grandes entreprises technologiques sont orient\u00e9s pour vous y maintenir autant que possible. Ils vous donnent donc toujours les choses les plus sensationnelles, les plus inhabituelles, les plus exceptionnelles \u00e0 lire, donc vous serez l\u00e0, vous serez l\u00e0.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est certain que le syst\u00e8me a totalement d\u00e9truit la valeur du contenu de l&rsquo;information, et avec des r\u00e9sultats comme celui que vous connaissez &#8211; M. Trump qui a 86 millions de followers sur twitter. Il dit que parfois, m\u00eame 20 tweets par jour, et que tous les m\u00e9dias am\u00e9ricains r\u00e9unis font 50 millions de copies par jour. Sur ces 50 millions, 10 millions sont destin\u00e9s aux journaux de qualit\u00e9, le New York Times, le Washington Post, le Wall Street Journal, quelque chose comme The Boston disparaissent, le Christian Science Monitor n&rsquo;est plus imprim\u00e9. Je veux dire que c&rsquo;est un groupe de journaux qui se r\u00e9duit lentement, tr\u00e8s lentement, et si vous touchez directement 80 millions de personnes, vous n&rsquo;avez pas besoin de 50 millions d&rsquo;exemplaires de la presse, encore moins des 10 millions d&rsquo;exemplaires du papier de qualit\u00e9, g\u00e9n\u00e9ralement d\u00e9pass\u00e9s.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le r\u00e9sultat est donc qu&rsquo;aujourd&rsquo;hui les journalistes, je ne parle pas des m\u00e9dias, les journalistes, sont de moins en moins pay\u00e9s. Aujourd&rsquo;hui, en Europe, nous avons beaucoup de jeunes journalistes qui \u00e9crivent des articles pour 20 euros par pi\u00e8ce. Ils ont besoin d&rsquo;obtenir des pr\u00eats. Le march\u00e9 les exploite donc en les payant moins. Une bonne gagne 10 euros de l&rsquo;heure, donc un journaliste est pay\u00e9 deux heures de bonne. Quand j&rsquo;\u00e9tais jeune journaliste, mon revenu mensuel \u00e9tait de 30 000 lires. On peut dire que c&rsquo;\u00e9tait un journaliste qui avait du succ\u00e8s, mais j&rsquo;avais quand m\u00eame 30 000 lires par mois. Ma secr\u00e9taire co\u00fbtait exactement trente mille lires par mois et je recevais trente mille lires avec deux articles. Aujourd&rsquo;hui, c&rsquo;est le contraire. Il n&rsquo;y a plus de contrats pour les syndicats, beaucoup de journaux n&rsquo;ont pas de contrat g\u00e9n\u00e9rique, et les syndicats ne peuvent pas les obliger \u00e0 adopter un contrat g\u00e9n\u00e9ral. En Italie maintenant, je ne sais pas combien d&rsquo;ann\u00e9es nous travaillons sans contrat g\u00e9n\u00e9ral. Donc la profession est en d\u00e9clin, les r\u00e9compenses pour la presse sont en d\u00e9clin, les m\u00e9dias sont en d\u00e9clin. Tout cela est un monde qui est en train de vivre des changements tr\u00e8s tr\u00e8s profonds.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un de mes amis m&rsquo;a appel\u00e9 pour me dire \u00ab\u00a0Roberto mon fils veut devenir journaliste, ma fille veut devenir journaliste, peux-tu les rencontrer et leur donner des conseils\u00a0\u00bb ? Je lui ai r\u00e9pondu : \u00ab\u00a0Attendez un instant, d&rsquo;abord, \u00eates-vous capable de les faire payer leur vie pendant 10 ans ? Si vous \u00eates capable de le faire, laissez-nous partir, sinon ce sera une frustration, parce qu&rsquo;ils vont commencer \u00e0 \u00e9crire, ils vont trouver que les m\u00e9dias les punissent pour avoir parl\u00e9 de&#8230; ils ne peuvent pas vivre avec \u00e7a, ils auront probablement une petite amie, quelqu&rsquo;un, comment voulez-vous qu&rsquo;ils survivent sans votre soutien ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il y a quelques jours, j&rsquo;ai lu un article tr\u00e8s int\u00e9ressant r\u00e9dig\u00e9 par l&rsquo;intelligence artificielle, \u00e0 qui l&rsquo;on a donn\u00e9 les mots cl\u00e9s et le syst\u00e8me. Deep View a parcouru l&rsquo;internet, a rassembl\u00e9 tous les \u00e9l\u00e9ments qui proviennent des donn\u00e9es de l&rsquo;internet et a \u00e9crit un article, c&rsquo;est ainsi que nous, robots, voulons vous rassurer, hommes, que nous n&rsquo;allons pas prendre votre place. Mais ensuite, j&rsquo;ai d\u00e9couvert que c&rsquo;\u00e9tait l&rsquo;instruction donn\u00e9e \u00e0 Deep Mind. Si l&rsquo;instruction donn\u00e9e \u00e0 Deep Mind \u00e9tait : \u00ab\u00a0\u00c9crivez que les robots vont d\u00e9passer l&rsquo;humanit\u00e9\u00a0\u00bb, ils auraient sans probl\u00e8me \u00e9crit l&rsquo;article exactement oppos\u00e9. Et la fa\u00e7on dont il \u00e9tait \u00e9crit n&rsquo;\u00e9tait pas un tr\u00e8s bon langage parce que c&rsquo;\u00e9tait en quelque sorte un langage m\u00e9canique, mais il \u00e9tait parfaitement publi\u00e9 dans un journal. C&rsquo;est une exp\u00e9rience qui a eu lieu il y a quelques semaines \u00e0 peine. Et une fois que nous aurons cette intelligence artificielle en place et qu&rsquo;un r\u00e9dacteur en chef dira au robot qu&rsquo;un avion s&rsquo;est \u00e9cras\u00e9 dans la ville de \u00ab\u00a0so\u00a0\u00bb, \u00e9crivez l&rsquo;article, il sera facile pour le robot de d\u00e9crire le crash, le cri d&rsquo;horreur des gens, l&rsquo;ambulance arrivant sur la piste, car qu&rsquo;est-ce que c&rsquo;est ? Des manifestations. S&rsquo;il y a une manifestation dans la rue, ils auront la m\u00eame histoire : combien de personnes&#8230; ? Donc, pour un robot, faire ce genre de journalisme serait tr\u00e8s simple, des \u00e9v\u00e9nements, des chroniques&#8230; Et en m\u00eame temps, aujourd&rsquo;hui, il est tr\u00e8s difficile de faire du journalisme mondial parce que&#8230;\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Je dois vous dire que je dois lire au moins cinq heures par jour pour avoir une id\u00e9e approximative de ce qui se passe dans le monde. Il faut savoir ce qui se passe en Asie, en Afrique, en Am\u00e9rique latine, en Europe, aux \u00c9tats-Unis&#8230; cela demande beaucoup de lecture&#8230; Et quand j&rsquo;\u00e9cris un article aujourd&rsquo;hui, le service de syndication des journaux ne prend pas plus de 650 mots. J&rsquo;\u00e9cris un article de deux mille, deux mille cinq cents, parce que pour expliquer la complexit\u00e9, je dois faire ressortir une approche holistique. Je ne peux pas \u00e9crire sur la Syrie sans impliquer la Turquie, les \u00c9mirats arabes unis, l&rsquo;Arabie saoudite. Je veux dire que tout n&rsquo;est que de nombreux angles d&rsquo;observation. Donc, si j&rsquo;\u00e9cris un tel article, je ne sais pas o\u00f9 le publier. Et si je le fais publier, \u00ab\u00a0El Pa\u00eds\u00a0\u00bb, en Espagne, qui est le journal le plus important d&rsquo;Espagne, le salaire des tr\u00e8s bons chroniqueurs, des \u00e9crivains tr\u00e8s c\u00e9l\u00e8bres, est de 80 euros par article. Je dois donc lire cinq heures par jour en esp\u00e9rant \u00eatre pay\u00e9 80 euros &#8211; ce qui est ce dont vous avez besoin pour d\u00e9jeuner avec votre ami.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le d\u00e9clin est donc un d\u00e9clin sous de nombreux angles. Je vous ai donn\u00e9 les plus importants. Il y en a aussi beaucoup d&rsquo;autres, mais ce sont les plus importants.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Merci, c&rsquo;\u00e9tait incroyablement int\u00e9ressant. Un autre point sur lequel j&rsquo;aimerais que vous reveniez un peu plus en arri\u00e8re parce que je n&rsquo;ai pas tout \u00e0 fait compris, et peut-\u00eatre que je ne l&rsquo;ai pas tout \u00e0 fait d\u00e9ball\u00e9, c&rsquo;est l&rsquo;impact du march\u00e9 sur les m\u00e9dias.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Laissez-moi aller sur le march\u00e9, parce que c&rsquo;est important.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Oui, s&rsquo;il vous pla\u00eet, s&rsquo;il vous pla\u00eet &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">parce que c&rsquo;est important &#8211;\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">veuillez revenir en arri\u00e8re et corriger certaines des choses que je n&rsquo;ai pas pu obtenir.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">D&rsquo;accord.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Qu&rsquo;enseignez-vous le premier jour d&rsquo;un cours de journalisme ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Qui, comment, o\u00f9, pourquoi, quand. Le 5w.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N&rsquo;oubliez pas que c&rsquo;est la premi\u00e8re chose que vous apprendrez. En fait, il s&rsquo;agissait de cr\u00e9er un code de communication avec les gens qui remplirait ces points n\u00e9cessaires pour que les gens comprennent pleinement un \u00e9v\u00e9nement. Mais cela n&rsquo;a rien \u00e0 voir avec l&rsquo;analyse. C&rsquo;est la fa\u00e7on dont vous rapportez. Comment cela se passe-t-il ? Pourquoi cela se produit-il ? Qui \u00e9tait l\u00e0 quand cela s&rsquo;est produit ? O\u00f9 cela se passe-t-il ? Ces cinq W sont tr\u00e8s utiles pour couvrir un \u00e9v\u00e9nement. Rappelons-nous que les journaux \u00e9taient en comp\u00e9tition les uns avec les autres pour savoir qui serait le premier \u00e0 couvrir un \u00e9v\u00e9nement, car \u00e0 l&rsquo;\u00e9poque, c&rsquo;\u00e9tait un \u00e9l\u00e9ment tr\u00e8s important. Mais ce genre de le\u00e7ons que vous recevez \u00e0 l&rsquo;\u00e9cole de journalisme ne vous pr\u00e9pare pas \u00e0 un travail plus complexe qui est un travail d&rsquo;analyse. Si vous \u00e9crivez un article, vous devez normalement aller au-del\u00e0 de l&rsquo;\u00e9v\u00e9nement. Vous devez replacer cet \u00e9v\u00e9nement dans son cadre pour lui donner une r\u00e9elle signification. Sinon, ce n&rsquo;est qu&rsquo;un \u00e9v\u00e9nement en soi &#8211; mais les \u00e9v\u00e9nements ne sont que la base de la r\u00e9alit\u00e9, vous devez construire sur cette r\u00e9alit\u00e9 pour donner au lecteur, au lecteur la capacit\u00e9 d&rsquo;aller au-del\u00e0 des \u00e9v\u00e9nements. Disons que le prix du th\u00e9 a augment\u00e9. Pourquoi a-t-il augment\u00e9 ? Qui en sont les b\u00e9n\u00e9ficiaires ? Qui travaille sur le terrain ? Seulement les femmes. Le changement du prix, a-t-il affect\u00e9 la vie de ces femmes ? O\u00f9 est pass\u00e9 l&rsquo;argent de l&rsquo;augmentation ? Car le fait que le prix ait augment\u00e9 de sept cents ne signifie rien en soi. Je veux donc dire que le vrai journalisme consiste \u00e0 pouvoir analyser, rassembler toutes les donn\u00e9es, de sorte que votre lecteur dispose de nombreux \u00e9l\u00e9ments sur lesquels il peut se baser pour comprendre. Maintenant, ce qui se passe, c&rsquo;est que le march\u00e9 a r\u00e9duit ce type de journalisme parce que ce type de journalisme va co\u00fbter de l&rsquo;argent, va co\u00fbter du temps. Si vous envoyez un journaliste au Y\u00e9men avec un t\u00e9l\u00e9porteur, au maximum deux ou trois jours apr\u00e8s, il doit commencer \u00e0 envoyer des articles. Maintenant, pour aller au Y\u00e9men et pour comprendre la situation, il vous faudra au moins une semaine. Le journalisme devient donc de plus en plus superficiel car le march\u00e9 ne r\u00e9compense pas les journalistes simplement parce que l&rsquo;argent est ailleurs. Donc, si vous \u00eates r\u00e9dacteur en chef, \u00e9diteur d&rsquo;un journal, et que vous devez survivre, vous devez faire des choix. Et quel choix ferez-vous ? Je vendrai ce qui est le plus simple, pas ce qui est le plus complexe. Je vendrai ce qui est plus familier, pas quelque chose pour lequel je fais beaucoup d&rsquo;explications pour situer le lecteur avec un processus. La qualit\u00e9 des revues que nous avons est donc en baisse parce que le march\u00e9 ne r\u00e9compense pas les m\u00e9dias. Le march\u00e9 est all\u00e9 ailleurs, il est all\u00e9 vers les m\u00e9dias sociaux. Et pour survivre, les m\u00e9dias ont d\u00fb r\u00e9duire leur qualit\u00e9, leur analyse.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aussi parce qu&rsquo;en m\u00eame temps, les personnes qui lisent ont de moins en moins de capacit\u00e9 d&rsquo;attention, de moins en moins de temps. Ils sont submerg\u00e9s par des millions d&rsquo;informations dans lesquelles ils doivent choisir pour pouvoir trouver ce qu&rsquo;ils veulent. Et en cela, le moteur de recherche, ou Google, Facebook, n&rsquo;aide pas &#8211; parce qu&rsquo;ils ne vous aident pas \u00e0 trouver ce qui est plus important, mais ce qui est plus glamour.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le march\u00e9 a donc modifi\u00e9 la relation des m\u00e9dias avec le lecteur et des m\u00e9dias avec la qualit\u00e9.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lorsque \u00ab\u00a0Prensa Latina\u00a0\u00bb, l&rsquo;agence de presse de Cuba, a \u00e9t\u00e9 cr\u00e9\u00e9e, elle a \u00e9t\u00e9 lanc\u00e9e par un journaliste argentin. Il y est all\u00e9 et il y avait encore la dictature de Batista, alors il s&rsquo;est habill\u00e9 en pr\u00eatre pour atteindre la zone de gu\u00e9rilla. Il a pass\u00e9 quelques jours avec Fidel Castro et ainsi de suite. Il est donc sorti et a \u00e9crit le livre sur la gu\u00e9rilla, qui a \u00e9t\u00e9 le premier livre \u00e0 expliquer ce qui se passait r\u00e9ellement, parce que jusqu&rsquo;alors les agences de presse am\u00e9ricaines \u00e9taient pro-batista, pas pour Fidel Castro. Ce type s&rsquo;appelait donc Masetti. Masetti est retourn\u00e9 \u00e0 Cuba \u00e0 la fin de la dictature. Et il a fait une \u00e9mission \u00e0 la radio qui disait : C&rsquo;est terrible, personne ne conna\u00eet la situation \u00e0 Cuba, parce que les journalistes \u00e9crivent sur Cuba de l&rsquo;ext\u00e9rieur, le front am\u00e9ricain est uni contre Fidel Castro, donc l&rsquo;Europe suit&#8230; beaucoup d&rsquo;intellectuels suivent&#8230; Alors un jour Che Guevara l&rsquo;a appel\u00e9 et il a dit \u00e0 Masetti : Tu sais quoi : fais une agence de presse pour que nous puissions r\u00e9futer AP, UP, tous ces mots des agences internationales. Et Masetti, qui n&rsquo;\u00e9tait pas un vrai grand journaliste, et pas un manager, s&rsquo;est retrouv\u00e9 charg\u00e9 de cr\u00e9er une agence de presse. Ce qu&rsquo;il a fait, c&rsquo;est qu&rsquo;il a pris les meilleures personnes en Am\u00e9rique latine, Gabriel Garcia Marquez, les meilleures personnes et les a engag\u00e9es comme journalistes. Et Prensa Latina a fait des articles bien, bien, bien sup\u00e9rieurs \u00e0 ce qui circulait. Ils \u00e9taient \u00e9crits par des artistes, des artistes vraiment importants. Et ce qu&rsquo;ils faisaient, c&rsquo;\u00e9tait&#8230; Je vais vous dire, vous avez la carte des villes pleines d&rsquo;Am\u00e9rique latine et puis ils sont all\u00e9s \u00e0 AP, o\u00f9 dans un flash ils ont dit qu&rsquo;il y a une manifestation au Guatemala, \u00e0 propos de ces flashes, alors ils ont pris la carte de la ville du Guatemala et ont \u00e9crit un article. \u00ab\u00a0Devant les gens, il y a un groupe de jeunes qui crient \u00ab\u00a0Libert\u00e9 ! Libert\u00e9 ! La police charge depuis la rue\u00a0\u00bb. &#8211; Ils inventaient tout, mais comme toutes les manifestations se d\u00e9roulent ainsi, l&rsquo;histoire est pass\u00e9e \u00e0 l&rsquo;AP et dans la presse. La Prensa Latina avait des plaines qui parachutaient des journalistes dans les moments des \u00e9v\u00e9nements pour couvrir cette manifestation. Il y avait si peu de gens \u00e0 La Havane et cela n&rsquo;a men\u00e9 nulle part.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour vous dire que cette \u00e9criture d&rsquo;un \u00e9v\u00e9nement est simple parce qu&rsquo;elle est toujours la m\u00eame. L&rsquo;analyse d&rsquo;un \u00e9v\u00e9nement est tr\u00e8s compliqu\u00e9e et pour avoir une autorit\u00e9 sur les \u00e9v\u00e9nements, il faut en avoir une : A &#8211; un type capable de le faire ; B &#8211; un journal capable de le publier ; C &#8211; un int\u00e9r\u00eat du public \u00e0 le lire. Ces trois choses sont en d\u00e9clin, et c&rsquo;est l\u00e0 le v\u00e9ritable d\u00e9clin du journalisme.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Je vous remercie. Je crois que j&rsquo;ai tout compris, la partie sur le march\u00e9, ainsi que cette partie, donc je ne vais pas la passer en revue. Si je pouvais, je poserais quelques questions sur certaines histoires qui existent, qui flottent, qui ont un rapport avec le d\u00e9clin, juste pour avoir votre point de vue sur elles. L&rsquo;une d&rsquo;entre elles est en quelque sorte, je vais la regrouper, donc c&rsquo;est le point de vue de Noam Chomsky sur la propagande, comme \u00ab\u00a0Manufacturing Consent\u00a0\u00bb et cela va aussi dans le sens de ce qu&rsquo;Edward Bernays a fait &#8211; je veux dire comment les relations publiques aux \u00c9tats-Unis ont adopt\u00e9 ce point de vue propagandiste.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Cela d\u00e9pend de l&rsquo;angle sous lequel vous abordez la question. Si vous regardez sous l&rsquo;angle d&rsquo;un journaliste et des m\u00e9dias, la r\u00e9ponse est tr\u00e8s simple. Il y a toujours eu deux pouvoirs qui essaient de contr\u00f4ler la communication : l&rsquo;\u00c9tat et le march\u00e9. Les personnes ayant un int\u00e9r\u00eat commercial essaient de contr\u00f4ler les m\u00e9dias pour renforcer leur int\u00e9r\u00eat commercial. Les personnes qui ont une vision politique essaient d&rsquo;utiliser les m\u00e9dias pour pr\u00e9senter leur vision politique. Et c&rsquo;est avec l&rsquo;arriv\u00e9e des m\u00e9dias de masse qu&rsquo;ils commencent. Si vous prenez l&rsquo;\u00e9poque de disons 1820, le Times \u00e9tait un journal pour les \u00e9lites. Il s&rsquo;est vendu \u00e0 25 000 exemplaires. Il \u00e9tait extr\u00eamement bien \u00e9crit. Une fois qu&rsquo;ils \u00e9taient \u00e9crivains, il y avait aussi des journalistes. Aujourd&rsquo;hui, ils n&rsquo;existent plus.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Donc The Citizen Kane, qui invente une guerre avec Cuba, est une manipulation. Mais de tous les temps, des gens de pouvoir financier ou des gens d&rsquo;int\u00e9r\u00eats politiques essaient de contr\u00f4ler les m\u00e9dias. Bien s\u00fbr, si vous regardez d&rsquo;un point de vue sociologique, c&rsquo;est un ph\u00e9nom\u00e8ne beaucoup plus large &#8211; c&rsquo;est ainsi que le syst\u00e8me essaie d&rsquo;atteindre et de contr\u00f4ler la soci\u00e9t\u00e9. Dans ce sens, jusqu&rsquo;aux ann\u00e9es 50, les m\u00e9dias \u00e9taient le seul moyen de communication. Ils \u00e9taient donc beaucoup plus importants qu&rsquo;aujourd&rsquo;hui. Mais regardez-les, la technique \u00e9tait la suivante : il fallait \u00e9crire un livre, un faux livre, comme The Whites, The Whites of Zion, pour que les gens deviennent antis\u00e9mites, mais c&rsquo;\u00e9tait \u00e0 l&rsquo;\u00e9poque de Gutenberg, il fallait imprimer le livre, le distribuer, organiser un syst\u00e8me pour faire de la propagande politique, ou une voix dans la rue. Aujourd&rsquo;hui, il existe mille fa\u00e7ons de faire de la propagande politique. Les fausses nouvelles en sont le meilleur exemple. Nous avons aujourd&rsquo;hui un certain nombre de Fake News chaque jour, qui apparaissent sur notre \u00e9cran, et qui sont impressionnantes. Regardez comment Bannon ou Trump, ont utilis\u00e9 les m\u00e9dias, les m\u00e9dias sociaux prenant le dessus sur les m\u00e9dias pour convaincre les gens qu&rsquo;il y aura des fraudes aux \u00e9lections. Se souciait-il des m\u00e9dias ? Il ne s&rsquo;en souciait pas du tout. Et pourtant, il a pu toucher 71 millions de personnes, et aujourd&rsquo;hui, 83 % des r\u00e9publicains pensent qu&rsquo;il y a eu une fraude. C&rsquo;est donc quelque chose qui remonte \u00e0 l&rsquo;\u00e9poque de Goebbels. Mais Goebbels, en tant que ministre d&rsquo;Hitler, pour atteindre les gens, il ne pouvait utiliser que la radio, les manifestations de masse et les m\u00e9dias. Aujourd&rsquo;hui, pour Goebbels, il serait immens\u00e9ment plus facile de faire son travail. Parce que vous&#8230; dans ce monde de Zuckerberg, tout est \u00e9gal. Il n&rsquo;y a plus de syst\u00e8me de valeurs locales.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Je comprends donc qu&rsquo;il y a toujours eu deux pouvoirs qui essayaient de s&#8217;emparer des m\u00e9dias, c&rsquo;est-\u00e0-dire l&rsquo;entreprise et l&rsquo;\u00c9tat. Mais en m\u00eame temps, ce sont les gens qui sont cens\u00e9s pouvoir contr\u00f4ler, ou du moins \u00e9lire l&rsquo;\u00c9tat qui est cens\u00e9 garder le march\u00e9 sous contr\u00f4le. Deux questions se posent donc pour moi \u00e0 partir de l\u00e0, ou \u00e9mergent. L&rsquo;entreprise, le march\u00e9, Wall Street essayait de capturer l&rsquo;\u00c9tat et de contr\u00f4ler ce qui se passait. Sont-ils diff\u00e9rents \u00e0 ce stade et quel est le rapport avec le monde des m\u00e9dias ?\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Ici, vous devez faire une diff\u00e9rence tr\u00e8s fondamentale. Il y a trois angles. Le premier est de savoir si vous \u00eates dans une d\u00e9mocratie ou dans un r\u00e9gime autocratique ou dictatorial. Dans un r\u00e9gime dictatorial, l&rsquo;\u00c9tat et le march\u00e9 co\u00efncident. L&rsquo;\u00e9conomie chinoise co\u00efncide avec l&rsquo;\u00c9tat. Ce n&rsquo;est pas la situation, disons, des \u00c9tats-Unis. Mais aux \u00c9tats-Unis, le syst\u00e8me de valeurs de Trump et des entreprises est tr\u00e8s semblable. Donc, en d\u00e9mocratie, vous aurez un syst\u00e8me de valeurs o\u00f9 les deux int\u00e9r\u00eats pourraient co\u00efncider ou ne pas co\u00efncider du tout. En Argentine, les entreprises sont toujours contre le gouvernement. Et au Chili, les entreprises sont essentiellement aux c\u00f4t\u00e9s du gouvernement. Cela signifie que lorsque le gouvernement a la m\u00eame valeur sur l&rsquo;\u00e9conomie que le march\u00e9, il n&rsquo;y a pas de diff\u00e9rence.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce qu&rsquo;il est important de noter dans tout cela, c&rsquo;est comment les choses ont chang\u00e9 depuis l&rsquo;arriv\u00e9e de l&rsquo;\u00e8re Zuckerberg, car l&rsquo;\u00e8re Zuckerberg a cr\u00e9\u00e9 un syst\u00e8me inconnu dans l&rsquo;histoire, dans lequel les lecteurs deviennent des objets, deviennent des consommateurs. Les citoyens deviennent d&rsquo;abord des consommateurs, parce que cela vous pousse \u00e0 acheter ceci et cela, mais ils deviennent aussi des objets parce qu&rsquo;ils vous classent selon votre int\u00e9r\u00eat, vos choix, vos go\u00fbts, et vous regroupent avec des personnes similaires. Donc si Nestl\u00e9 veut vendre un tr\u00e8s bon chocolat, vous allez l\u00e0-bas et vous dites Qui sont les gens qui ont un go\u00fbt exquis et on dira : \u00ab\u00a0OK, je peux vous donner deux millions d&rsquo;e-mails, combien vous me donnez ? Et ainsi nous devenons des objets. Nous ne sommes plus seulement des consommateurs. Cela avec l&rsquo;information \u00e9tait impossible. C&rsquo;\u00e9tait impossible. Cela a donc chang\u00e9 la relation entre le march\u00e9 et les m\u00e9dias. Les m\u00e9dias ne sont plus aussi pertinents qu&rsquo;avant, les m\u00e9dias sociaux sont devenus plus pertinents.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais quel est le syst\u00e8me de valeurs de la grande entreprise de la Silicon Valley ? Exactement le m\u00eame que celui des b\u00e9n\u00e9fices qui sont partag\u00e9s par les entreprises de combustibles fossiles, comme les entreprises charbonni\u00e8res. Vous pouvez certainement dire que les compagnies de charbon n&rsquo;ont rien \u00e0 voir avec Zuckerberg. Jusqu&rsquo;\u00e0 un certain point, car dans la vie r\u00e9elle, elles partagent les m\u00eames int\u00e9r\u00eats. Donc si vous voulez faire un journal, vous avez l&rsquo;attaque traditionnelle habituelle des entreprises, mais maintenant vous avez une nouvelle attaque qui est la domination sans pr\u00e9c\u00e9dent des gens, par quelques entreprises technologiques. Aujourd&rsquo;hui, Facebook compte 2 milliards de lecteurs, milliards d&rsquo;utilisateurs. Je veux dire que la Chine compte 1,350 milliard de personnes. Le monde de Facebook en a plus. Et ils globalisent le monde et mettent les gens d&rsquo;Afrique, d&rsquo;Asie, d&rsquo;Am\u00e9rique latine dans le m\u00eame groupe de cat\u00e9gorie &#8211; donc ils standardisent le monde. Le monde va devenir de moins en moins d\u00e9mocratique, parce que la d\u00e9mocratie est faite de points de vue pluriels et de ce d\u00e9bat, plus il y a de points de vue pluriels, plus il y a de d\u00e9mocratie. Aujourd&rsquo;hui, nous avons de moins en moins de points de vue. Et les diff\u00e9rences entre les r\u00e9gions disparaissent vraiment, de l&rsquo;Europe au Japon. Allez \u00e0 un mariage japonais, il n&rsquo;y a rien d&rsquo;original, de traditionnel, les mariages japonais sont des mariages occidentaux, la musique occidentale, le style occidental. Tout cela est d\u00fb \u00e0 la mondialisation qui a une valeur politique, une valeur n\u00e9olib\u00e9rale, mais une valeur technologique, c&rsquo;est-\u00e0-dire ces soci\u00e9t\u00e9s d&rsquo;extraction, Google, Facebook, etc. Sociologiquement, nous allons dans la m\u00eame direction.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><i><span style=\"font-weight: 400;\">Je pense que c&rsquo;est un point tr\u00e8s int\u00e9ressant, mais je pense que maintenant nous nous d\u00e9veloppons plus dans la partie politique que dans la partie sur le r\u00f4le des m\u00e9dias, donc je vais essayer de revenir au sujet qui est la partie sur le r\u00f4le des m\u00e9dias, parce que j&rsquo;ai un million de questions suppl\u00e9mentaires \u00e0 ce sujet, comme tout ce que vous venez de dire, mais peut-\u00eatre que nous pouvons&#8230; je peux le garder pour une autre fois. Le r\u00f4le des m\u00e9dias est semblable \u00e0 ceux qui sont si importants, c&rsquo;est donc une question plus difficile parce qu&rsquo;une sorte de question sur la fa\u00e7on d&rsquo;interroger les m\u00e9dias est celle qui est cens\u00e9e informer le public et les gens afin qu&rsquo;ils puissent exercer dans une soci\u00e9t\u00e9 d\u00e9mocratique au moins une sorte de contr\u00f4le et d&rsquo;\u00e9lections, sur l&rsquo;\u00c9tat. Donc, si les m\u00e9dias sont captur\u00e9s soit par l&rsquo;\u00c9tat, soit par le march\u00e9, soit par les deux, soit compl\u00e8tement dans un \u00e9tat de euh compl\u00e8tement dans cet \u00c9tat, o\u00f9 l&rsquo;\u00e8re Zuckerberg, comme vous l&rsquo;appelez, a tant de points de vue similaires qui sont comme le glamour qui compte et non les vrais qui comptent et que les journalistes ne peuvent pas aimer faire comme de bons articles informatifs. Quel espoir voyez-vous pour nous et quelle voie voyez-vous pour nous sortir de ce cercle vicieux, je dirais, afin d&rsquo;avoir de bonnes informations pour que les gens puissent avoir de bonnes perspectives de la r\u00e9alit\u00e9 pour qu&rsquo;ils puissent \u00e9lire de bons fonctionnaires pour que les fonctionnaires puissent.\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Oui, je vous ai dit qu&rsquo;il y aura peu de journaux de haute qualit\u00e9. Aux \u00c9tats-Unis, il y en aura trois : New York Times, Washington Post, Wall Street Journal. Je ne pense pas que beaucoup d&rsquo;autres survivront. Et puis vous aurez l&rsquo;utilisateur du net pour distribuer des informations sp\u00e9cialis\u00e9es. J&rsquo;ai moi-m\u00eame fait cette exp\u00e9rience avec Other News. J&rsquo;ai commenc\u00e9 \u00e0 distribuer \u00e0 mes amis tous les jours deux nouvelles, deux articles, qui sont analytiques, qui ne sortiraient pas normalement dans le journal. Eh bien, j&rsquo;ai 20 000 personnes qui lisent les Autres nouvelles, parce qu&rsquo;elles d\u00e9couvrent que quelqu&rsquo;un a lu pour elles beaucoup de nouvelles, les trouve, s\u00e9lectionne les deux et leur \u00e9pargne beaucoup de travail. Il en va de m\u00eame pour les personnes qui s&rsquo;int\u00e9ressent \u00e0 la destruction du plastique. S&rsquo;il existe un bon service qui conserve aujourd&rsquo;hui la mani\u00e8re de d\u00e9truire le plastique, nous aurons beaucoup de gens qui iront l\u00e0-bas parce qu&rsquo;ils ont un int\u00e9r\u00eat sp\u00e9cifique. Other News est un mondialiste. Il n&rsquo;y aura pas beaucoup de mondialistes. L&rsquo;exemple qu&rsquo;on y trouve est un bon exemple. Nous n&rsquo;avons jamais fait de publicit\u00e9, mais nous sommes \u00e0 vingt mille. Ce n&rsquo;est rien. C&rsquo;est beaucoup, parce que ce sont des gens qui lisent des documents longs et complexes, mais c&rsquo;est la limite. Je pense donc qu&rsquo;\u00e0 l&rsquo;avenir il y aura peu de journaux de qualit\u00e9, qu&rsquo;un syst\u00e8me d&rsquo;information utilisera Internet pour donner des informations sur des questions sp\u00e9cialis\u00e9es, des questions mondiales auxquelles les gens de toutes les parties du monde peuvent s&rsquo;identifier, le changement climatique, si vous avez un bon syst\u00e8me de changement climatique, vous aurez des gens pr\u00eats \u00e0 lire cela. Mais c&rsquo;est un probl\u00e8me. Personne ne paie rien sur Internet. Tout le monde a l&rsquo;habitude de l&rsquo;obtenir gratuitement. Et si vous voulez introduire un syst\u00e8me d&rsquo;abonnement, vous devez faire comme le New York Times, maintenant je pense que c&rsquo;est deux dollars par mois, 0,49 par semaine, quelque chose comme \u00e7a. Donc avec cela, vous ne pourrez jamais obtenir l&rsquo;argent que vous aviez avant, avec la publicit\u00e9 qui est bonne, pour payer de tr\u00e8s bons journalistes d&rsquo;investigation. Vous aurez du mat\u00e9riel que vous r\u00e9cup\u00e9rerez sur votre front. Et ce sera un moteur fabriqu\u00e9 par des humains, qui recherchera les documents les plus significatifs, sur un th\u00e8me, sur le sujet et les rassemblera pour un public mondial qui se forme. C&rsquo;est ce qui va se passer, je pense. Peu de papiers de qualit\u00e9 et le nombre de syst\u00e8mes d&rsquo;information, pas de communication parce que dans Other News par exemple, nous ne demandons pas aux lecteurs de donner leur avis. Ce n&rsquo;est pas un espace horizontal. Nous utilisons l&rsquo;internet comme un syst\u00e8me vertical, parce que si vous l&rsquo;ouvrez comme un espace horizontal, vous allez devenir fou. Nous allons avoir des gens qui vont \u00e9crire les histoires les plus extravagantes. Si vous devez y r\u00e9pondre, alors vous devez avoir des gens capables de r\u00e9pondre avec comp\u00e9tence et bon sens. Cela co\u00fbte de l&rsquo;argent. Ce que je veux dire, c&rsquo;est que nous n&rsquo;avons plus les moyens de faire du bon journalisme, sauf dans quelques cas.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">D&rsquo;accord, merci. Je suis abonn\u00e9 \u00e0 Other News et je l&rsquo;appr\u00e9cie. Je fais confiance \u00e0 Other News parce que je sais que vous le faites. Mais pour les autres, je ne sais pas vraiment moi-m\u00eame comment je gagnerais ma confiance, en cette \u00e8re de m\u00e9fiance, o\u00f9 il y a tant de choses qui sont comme \u00e7a, c&rsquo;est parce qu&rsquo;il y a ces principaux journaux que vous avez dit, le New York Times Wall Street Journal et le Washington Post, et ils ont perdu beaucoup de lecteurs et de confiance. Je dirais donc que je ne suis m\u00eame pas s\u00fbr moi-m\u00eame, si je devais lire le New York Times, s&rsquo;il y a une valeur \u00e0 lire le New York Times, le Washington Post, s&rsquo;il y a une valeur \u00e0 les lire. Et si nous ne lisons pas ceux qui ont une sorte de pr\u00e9jug\u00e9, je ne sais pas si c&rsquo;est mauvais, mais je pense que c&rsquo;est plut\u00f4t mauvais. Comment trouver des m\u00e9dias alternatifs comme Other News en qui nous pouvons avoir confiance ou comment \u00e9tablir une confiance en eux, comme je sais comment faire confiance \u00e0 Other News parce que je vous connais, mais comment faire confiance aux autres ?\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Eh bien, il faut chercher quatre questions : 1 &#8211; Qui est le propri\u00e9taire, comment est la propri\u00e9t\u00e9, si la propri\u00e9t\u00e9 est divis\u00e9e entre diff\u00e9rentes personnes, vous aurez plus de confiance que s&rsquo;il s&rsquo;agit d&rsquo;une seule personne. Deuxi\u00e8mement, s&rsquo;agit-il d&rsquo;une entreprise \u00e0 but lucratif et non lucratif, qu&rsquo;est-ce que c&rsquo;est ? Troisi\u00e8mement, les objectifs, qui sont les buts de cette association. Et quatrei\u00e8mement, dans quelle mesure doit-elle rendre des comptes \u00e0 ses membres ? Ce sont les quatre questions. Donc, dans Other News, nous disons : nous sommes \u00e0 but non lucratif, nous sommes une association de journalistes, tout dirigeant peut devenir membre de l&rsquo;association et voter pour le conseil d&rsquo;administration. Dans notre budget, qui est transparent, et cela r\u00e9sout g\u00e9n\u00e9ralement beaucoup de probl\u00e8mes. Bien s\u00fbr, les gens vont demander : ces gens sont de droite, de gauche, croient en Dieu, ne croient pas en Dieu ? Et cela, vous ne pouvez pas l&rsquo;\u00e9viter, car c&rsquo;est ainsi que nous avons divis\u00e9 les lecteurs aujourd&rsquo;hui gr\u00e2ce \u00e0 Facebook, Google. Les gens sont divis\u00e9s en bulles, et les gens de la bulle A vont essayer de comprendre si vous pouvez \u00eatre mis dans la bulle A ou si vous \u00eates trop loin de la bulle A. Mais vous savez ce qui va se passer : la confiance va se passer en ayant les r\u00e9ponses \u00e0 ces questions. Qui sont les propri\u00e9taires, pourquoi font-ils cette publication&#8230; Je l&rsquo;ai fait en choisissant les fameux cinq W qu&rsquo;on nous a appris \u00e0 l&rsquo;\u00e9cole. Pourquoi cette publication, qui fait cette publication, o\u00f9 est cette publication, pour qui est faite cette publication ? Lorsque vous comprenez ces questions, vous avez jou\u00e9 aussi \u00e9quitablement que possible.\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Ma derni\u00e8re question porte sur une derni\u00e8re perspective sur le d\u00e9clin des m\u00e9dias qui existe, qui coule, partout o\u00f9 j&rsquo;ai vu et que je me demande comment vous vous y rattachez, si vous l&rsquo;avez vu, si vous ne l&rsquo;avez pas vu. Il y a cette histoire que je vais essayer de r\u00e9sumer et je ne suis pas tr\u00e8s bon pour reprendre les choses mais je vais faire de mon mieux. C&rsquo;est euh c&rsquo;est \u00e0 propos de l&rsquo;explication du postmodernisme. Il y a donc cette histoire qui, lentement, lentement apr\u00e8s la chute, enfin la chute du communisme je suppose, ou comme lorsque le communisme a \u00e9t\u00e9 montr\u00e9 comme faisant des choses atroces parce qu&rsquo;il est devenu le stalinisme, le point de vue marxiste des intellectuels, comme Michel Foucault et d&rsquo;autres comme lui, ils sont entr\u00e9s dans une phase postmoderniste, en disant qu&rsquo;il n&rsquo;y a pas de r\u00e9alit\u00e9, qu&rsquo;il n&rsquo;y a pas d&rsquo;histoire qui ne soit pas, qui ne soit pas vue d&rsquo;un certain point de vue. Et cela a \u00e9volu\u00e9 au cours des \u00e2ges, de sorte que la vision post-moderniste n&rsquo;est pas exactement la m\u00eame. Elle a \u00e9volu\u00e9, comme si elle \u00e9tait pass\u00e9e des intellectuels \u00e0 l&rsquo;activisme de gauche et \u00e0 l&rsquo;activisme progressiste de gauche et maintenant il y a beaucoup de factions qui proposent beaucoup, beaucoup d&rsquo;histoires.\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Le probl\u00e8me est que cette question conceptuelle co\u00efncide avec un moment particulier de notre histoire, \u00e0 savoir que nous sommes pass\u00e9s de la chute du communisme, de la chute du mur de Berlin, \u00e0 vingt ans de n\u00e9olib\u00e9ralisme absolu sans aucune critique, de capitalisme sans aucun contr\u00f4le, de capitalisme sauvage. Le capitalisme \u00e9tait la solution \u00e0 tout, le march\u00e9 a remplac\u00e9 les hommes, et cela a dur\u00e9 20 ans sans aucun d\u00e9bat. Puis, en 2008, nous avons eu la crise financi\u00e8re. Et puis la peur a commenc\u00e9 \u00e0 venir. La peur des immigr\u00e9s, qui deviennent le bouc \u00e9missaire, la peur de, est-ce que je trouverais un emploi, ce qui sera ma vie, est-ce que je pourrai avoir une pension quand je prendrai ma retraite. Les jeunes surtout ont beaucoup d&rsquo;incertitudes et de craintes. Et quand vous mettez l&rsquo;incertitude, quand vous mettez&#8230; l&rsquo;avidit\u00e9 et la peur ensemble, vous mettez les deux moteurs de l&rsquo;histoire en marche. Donc, pendant que nous avons cette chose en cours, parall\u00e8lement aux diff\u00e9rentes factions de ce dont vous parlez, du monde postmoderniste, un autre facteur est venu, qui \u00e0 mon avis \u00e9tait beaucoup plus pertinent que le d\u00e9bat intellectuel, \u00e0 savoir que les gens ont commenc\u00e9 \u00e0 ne plus croire en rien qui puisse \u00eatre accus\u00e9 de coop\u00e9rer avec l&rsquo;\u00e9lite. Les gens de la campagne \u00e9taient contre la ville. Il y avait des clubs qui divisaient la ville. Il y avait un groupe qui pensait que la viande rouge est un probl\u00e8me s\u00e9rieux, les gens regardent la question syrienne, je veux dire qu&rsquo;il y avait beaucoup de factions qui ne s&rsquo;int\u00e9ressaient qu&rsquo;\u00e0 une seule question. Et ces factions \u00e9taient beaucoup, beaucoup, beaucoup plus nombreuses et beaucoup plus \u00e9motionnelles que le d\u00e9bat sur le postmodernisme. Je pense donc que ce que vous dites, c&rsquo;est qu&rsquo;on est submerg\u00e9 dans ce monde dans lequel nous sommes, qui est un monde en transition &#8211; vers lequel, franchement, je ne sais pas. Mais je sais que le syst\u00e8me dans lequel nous sommes est termin\u00e9. Il n&rsquo;y a plus de l\u00e9gitimit\u00e9, il n&rsquo;y a plus de cr\u00e9dibilit\u00e9, et il n&rsquo;y a plus de participation des gens. Aujourd&rsquo;hui, les gens ont \u00e9t\u00e9 totalement s\u00e9par\u00e9s des structures officielles. Je pense donc que ce que vous dites doit \u00eatre consid\u00e9r\u00e9 comme faisant partie d&rsquo;un changement sociologique, culturel et m\u00eame anthropologique beaucoup plus large.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aujourd&rsquo;hui, si vous prenez un&#8230; Le week-end dernier, j&rsquo;\u00e9tais avec des amis qui ont une petite fille de cinq ans. Donc on mange et cette fille \u00e9tait assise \u00e0 la table. A dix heures, je dis : quand est-ce que tu vas dormir ? Elle dit huit heures. Il est dix heures. Elle dit : ah mais quand il y a des adultes, j&rsquo;aime bien rester parce que j&rsquo;aime bien entendre la conversation. Maintenant, nous parlons du Moyen-Orient, alors j&rsquo;ai \u00e9t\u00e9 tr\u00e8s surpris. J&rsquo;ai dit ceci : Quel \u00e2ge avez-vous ? Elle a dit cinq ans. Donc je ne sais pas quoi dire, je dis bien que c&rsquo;est un bon \u00e2ge. Elle a point\u00e9 le doigt sur la table et m&rsquo;a dit : \u00ab\u00a0C&rsquo;est l&rsquo;\u00e2ge le plus difficile\u00a0\u00bb, ce \u00e0 quoi je dois r\u00e9fl\u00e9chir un peu si vous me demandez quel est l&rsquo;\u00e2ge le plus difficile. Maintenant, les parents, ont-ils dit, l&rsquo;am\u00e8nent au lit. Alors je l&rsquo;ai amen\u00e9e au lit, et elle s&rsquo;est couch\u00e9e parce qu&rsquo;avec moi elle allait se coucher et elle a dit : Raconte-moi une histoire. Maintenant je n&rsquo;ai plus de fils, je ne connais pas d&rsquo;histoires pour les enfants. Je ne me souviens pas de quelque chose \u00e0 propos de White Neige, je me souviens de l&rsquo;histoire d&rsquo;une fille avec un chapeau rouge, qui \u00e9tait dans un bois avec un loup, la grand-m\u00e8re, vous vous souvenez ? Du bois rouge, je crois ? Oui, oui, le Petit Chaperon Rouge. Alors j&rsquo;invente un nouveau Chaperon rouge et quand je dis \u00a0\u00bb et puis le Bois rouge se perd dans les bois &#8211; elle me regarde et dit : pourquoi n&rsquo;a-t-elle pas appel\u00e9 par t\u00e9l\u00e9phone ? C&rsquo;est un changement anthropologique parce que si vous regardez les choses avec les yeux de cette fille, cette petite fille, Rom\u00e9o et Juliette ne serait pas arriv\u00e9e. Juliette aurait appel\u00e9 Rom\u00e9o et lui aurait dit : \u00ab\u00a0Regarde, je vais prendre une drogue qui me fait croire que je suis morte\u00a0\u00bb. Ne vous inqui\u00e9tez pas, je ne suis pas mort, attendez un peu et je me r\u00e9veillerai. Rom\u00e9o ne se serait jamais suicid\u00e9, Juliette ne se serait pas suicid\u00e9e. Nous n&rsquo;aurions pas de Rom\u00e9o et Juliette. C&rsquo;est donc une nouvelle soci\u00e9t\u00e9 anthropologique et culturelle qui se profile. Dans laquelle l&rsquo;intelligence artificielle et intelligente va faire dispara\u00eetre de nombreux emplois, ce sera une soci\u00e9t\u00e9 que je ne peux que pr\u00e9voir. Votre question n&rsquo;est donc pas de savoir ce qui se passe maintenant mais ce qui se passera dans 20 ans, pas dans 100, 20 ans. Lorsque les voitures rouleront toutes seules, vous n&rsquo;aurez plus de conducteurs. Tout votre temps sera tr\u00e8s diff\u00e9rent, parce que vous travaillerez principalement non pas sur le contexte social mais sur l&rsquo;internet. Je veux dire que c&rsquo;est une soci\u00e9t\u00e9 diff\u00e9rente. Ce sera des gens diff\u00e9rents. Faites donc une petite projection de cette question.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Je pense que nous devrions en rester l\u00e0 pour aujourd&rsquo;hui, car vous avez \u00e9t\u00e9 tr\u00e8s g\u00e9n\u00e9reux de votre temps et vous m&rsquo;avez donn\u00e9 beaucoup de sujets de r\u00e9flexion, alors merci beaucoup.\u00a0<\/span><\/i><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Roberto Savio est journaliste, expert en communication, commentateur politique, militant pour la justice sociale et climatique et militant pour la gouvernance mondiale. Il est le fondateur et pr\u00e9sident \u00e9m\u00e9rite de l&rsquo;agence de presse Inter Press Service (IPS) et \u00e9diteur de Other News. J&rsquo;ai eu la chance de rencontrer Roberto gr\u00e2ce \u00e0 mon militantisme, et lorsque [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,31],"tags":[],"class_list":["post-805","post","type-post","status-publish","format-standard","hentry","category-articles","category-articles-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sur le d\u00e9clin et l&#039;\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sur le d\u00e9clin et l&#039;\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu\" \/>\n<meta property=\"og:description\" content=\"Roberto Savio est journaliste, expert en communication, commentateur politique, militant pour la justice sociale et climatique et militant pour la gouvernance mondiale. Il est le fondateur et pr\u00e9sident \u00e9m\u00e9rite de l&rsquo;agence de presse Inter Press Service (IPS) et \u00e9diteur de Other News. J&rsquo;ai eu la chance de rencontrer Roberto gr\u00e2ce \u00e0 mon militantisme, et lorsque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorin Ionescu\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-24T07:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-24T08:02:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\" \/>\n<meta name=\"author\" content=\"Sorin Ionescu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorin Ionescu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"37 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/\"},\"author\":{\"name\":\"Sorin Ionescu\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"headline\":\"Sur le d\u00e9clin et l&rsquo;\u00e9chec des m\u00e9dias &#8211; dialogue avec Roberto Savio\",\"datePublished\":\"2020-12-24T07:19:24+00:00\",\"dateModified\":\"2020-12-24T08:02:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/\"},\"wordCount\":7882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"articleSection\":[\"Articles\",\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/\",\"name\":\"Sur le d\u00e9clin et l'\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"datePublished\":\"2020-12-24T07:19:24+00:00\",\"dateModified\":\"2020-12-24T08:02:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/on-media-failure-and-decline-dialogue-with-roberto-savio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sorinionescu.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur le d\u00e9clin et l&rsquo;\u00e9chec des m\u00e9dias &#8211; dialogue avec Roberto Savio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/\",\"name\":\"Sorin Ionescu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sorinionescu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\",\"name\":\"Sorin Ionescu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"width\":126,\"height\":119,\"caption\":\"Sorin Ionescu\"},\"logo\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\"},\"sameAs\":[\"https:\\\/\\\/sorinionescu.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sur le d\u00e9clin et l'\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/","og_locale":"fr_FR","og_type":"article","og_title":"Sur le d\u00e9clin et l'\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu","og_description":"Roberto Savio est journaliste, expert en communication, commentateur politique, militant pour la justice sociale et climatique et militant pour la gouvernance mondiale. Il est le fondateur et pr\u00e9sident \u00e9m\u00e9rite de l&rsquo;agence de presse Inter Press Service (IPS) et \u00e9diteur de Other News. J&rsquo;ai eu la chance de rencontrer Roberto gr\u00e2ce \u00e0 mon militantisme, et lorsque [&hellip;]","og_url":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/","og_site_name":"Sorin Ionescu","article_published_time":"2020-12-24T07:19:24+00:00","article_modified_time":"2020-12-24T08:02:01+00:00","og_image":[{"url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","type":"","width":"","height":""}],"author":"Sorin Ionescu","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorin Ionescu","Dur\u00e9e de lecture estim\u00e9e":"37 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#article","isPartOf":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/"},"author":{"name":"Sorin Ionescu","@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"headline":"Sur le d\u00e9clin et l&rsquo;\u00e9chec des m\u00e9dias &#8211; dialogue avec Roberto Savio","datePublished":"2020-12-24T07:19:24+00:00","dateModified":"2020-12-24T08:02:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/"},"wordCount":7882,"commentCount":0,"publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"image":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","articleSection":["Articles","Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/","url":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/","name":"Sur le d\u00e9clin et l'\u00e9chec des m\u00e9dias - dialogue avec Roberto Savio ~ Sorin Ionescu","isPartOf":{"@id":"https:\/\/sorinionescu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#primaryimage"},"image":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","datePublished":"2020-12-24T07:19:24+00:00","dateModified":"2020-12-24T08:02:01+00:00","breadcrumb":{"@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#primaryimage","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png"},{"@type":"BreadcrumbList","@id":"https:\/\/sorinionescu.org\/articles\/on-media-failure-and-decline-dialogue-with-roberto-savio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sorinionescu.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Sur le d\u00e9clin et l&rsquo;\u00e9chec des m\u00e9dias &#8211; dialogue avec Roberto Savio"}]},{"@type":"WebSite","@id":"https:\/\/sorinionescu.org\/#website","url":"https:\/\/sorinionescu.org\/","name":"Sorin Ionescu","description":"","publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sorinionescu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae","name":"Sorin Ionescu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","width":126,"height":119,"caption":"Sorin Ionescu"},"logo":{"@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png"},"sameAs":["https:\/\/sorinionescu.org"]}]}},"_links":{"self":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":2,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/805\/revisions\/808"}],"wp:attachment":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}