{"id":890,"date":"2022-02-26T22:39:02","date_gmt":"2022-02-27T03:39:02","guid":{"rendered":"https:\/\/sorinionescu.org\/non-classifiee\/dissolution-de-lillusion-de-lego-jean-christophe-lurenbaum\/"},"modified":"2022-02-26T22:39:07","modified_gmt":"2022-02-27T03:39:07","slug":"dissolution-de-lillusion-de-lego-jean-christophe-lurenbaum","status":"publish","type":"post","link":"https:\/\/sorinionescu.org\/fr\/non-classifiee\/dissolution-de-lillusion-de-lego-jean-christophe-lurenbaum\/","title":{"rendered":"Dissolution de l&rsquo;illusion de l&rsquo;ego &#8211; Jean Christophe Lurenbaum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"890\" class=\"elementor elementor-890 elementor-882\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dd4ea4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1dd4ea4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d7aa5b\" data-id=\"9d7aa5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c51ee7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c51ee7d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37c3068\" data-id=\"37c3068\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c2d21d elementor-widget elementor-widget-image\" data-id=\"1c2d21d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg\" class=\"attachment-large size-large wp-image-884\" alt=\"\" srcset=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg 300w, https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1-150x150.jpeg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c7533a6\" data-id=\"c7533a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bada6c elementor-widget elementor-widget-text-editor\" data-id=\"1bada6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jean-Christophe a d\u00e9cid\u00e9 tr\u00e8s t\u00f4t de consacrer sa vie \u00e0 l\u2019organisation de la cr\u00e9ation d\u2019un plus grand bonheur dans le monde. Dans ce but, il a d\u2019abord suivi une formation d\u2019\u00e9conomiste et est devenu un strat\u00e8ge cl\u00e9 en charge des grands projets de la plus grande corporation publique fran\u00e7aise, La Poste. Il a \u00e9crit \u00ab\u00a0<a href=\"http:\/\/www.jcl.algosphere.org\/naitre-gratuit.pdf\">Na\u00eetre est-il dans l\u2019int\u00e9r\u00eat de l\u2019enfant? Id\u00e9ologie de reproduction versus non-souffrance<\/a>\u00a0\u00bb (2011), le r\u00e9sultat d\u2019une exploration historique de plusieurs d\u00e9cennies du conflit entre l\u2019\u00e9thique de la non-consommation et l\u2019id\u00e9ologie de la reproduction. En 2013, il a cofond\u00e9 l\u2019Algosphere Alliance, un r\u00e9seau et une d\u00e9mocratie directe pour soulager la souffrance.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e05cd1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7e05cd1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b00f5e6 elementor-widget elementor-widget-video\" data-id=\"b00f5e6\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/b00sP6BWubo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb8c61f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb8c61f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bbbefae\" data-id=\"bbbefae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cff815e elementor-widget elementor-widget-heading\" data-id=\"cff815e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Peut-\u00eatre que l'on peut   commencer par la d\u00e9finition de la dissolution de l'illusion de l'ego.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a958167 elementor-widget elementor-widget-text-editor\" data-id=\"a958167\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">J&rsquo;utilise un peu ce qu&rsquo;est ce qui est ce\u00a0 qui est dit par d&rsquo;autres notamment, par les \u00a0 bouddhistes. Donc l&rsquo;id\u00e9e\u00a0 centrale du bouddhisme, que\u00a0 je reprends, c&rsquo;est qu&rsquo; instinctivement on a\u00a0 le sentiment d&rsquo;\u00eatre soi. D&rsquo;avoir un ego, c&rsquo;est-\u00e0\u00a0 -dire, d&rsquo;\u00eatre une entit\u00e9 la m\u00eame et diff\u00e9rente\u00a0 \u00a0 des autres, et m\u00eame la m\u00eame entit\u00e9 au fil du\u00a0 temps. Je suis n\u00e9 Jean-Christophe \u00a0 un jour et\u00a0 je mourrai Jean-Christophe\u00a0 \u00e0 cent ans. Donc il y a cette id\u00e9e d&rsquo;\u00eatre soi \u00a0 et diff\u00e9rent des autres, voil\u00e0. Donc \u00e7a c&rsquo;est le sentiment d&rsquo;avoir un \u00e9go, on va\u00a0 qualifier \u00e7a comme \u00e7a, l&rsquo;impression d&rsquo;avoir \u00a0 un ego, et ce que ce qu&rsquo;a dit le bouddhisme c&rsquo;est que c&rsquo;est une illusion, cette impression \u00a0 c&rsquo;est une illusion mentale. Donc pour revenir \u00e0 ta\u00a0 question: \u00ab\u00a0Qu&rsquo;est-ce que\u00a0 dissoudre l&rsquo;illusion d&rsquo;ego?\u00a0\u00bb,\u00a0 et bien c&rsquo;est c&rsquo;est comprendre\u00a0 la nature de cette \u00a0 illusion mentale et r\u00e9ussir petit \u00e0 petit \u00e0 la\u00a0 faire reculer.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8271f elementor-widget elementor-widget-heading\" data-id=\"4a8271f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vous m'avez aussi dit que cette illusion est tr\u00e8s li\u00e9e, sinon   compl\u00e8tement identique \u00e0 l'illusion  du libre arbitre.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3aecd elementor-widget elementor-widget-text-editor\" data-id=\"eb3aecd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Alors elle est extr\u00eamement\u00a0 li\u00e9e, c&rsquo;est pas \u00e9quivalent, \u00a0 mais c&rsquo;est extr\u00eamement li\u00e9e.\u00a0 Euh, je veux dire que si quelqu&rsquo;un croit au libre arbitre, alors on\u00a0 peut \u00eatre s\u00fbr qu&rsquo;ils croient \u00e0 l&rsquo;ego, parce \u00a0 que pour qu&rsquo;il y est libre arbitre, il faudrait\u00a0 qu&rsquo;il y est arbitre; donc quelqu&rsquo;un qui croit au\u00a0 libre arbitre c&rsquo;est qu&rsquo;ils croient qu&rsquo;il ya un arbitre.\u00a0 c&rsquo;est la n\u00e9go c&rsquo;est la m\u00eame chose si on croit \u00a0 qu&rsquo;un arbitre c&rsquo;est qu&rsquo;on croit qu&rsquo;un ego. Voil\u00e0, donc ce qu&rsquo;on peut dire \u00a0 c&rsquo;est que si quelqu&rsquo;un \u00a0 croit au libre arbitre \u00e7a veut dire qu&rsquo;il croit\u00a0 \u00e0 l&rsquo;ego. C&rsquo;est dans ce sens que\u00a0 les deux concepts sont intimement li\u00e9s, voil\u00e0.\u00a0 Lors d&rsquo;ailleurs, d&rsquo;ailleurs croire au libre arbitre, de\u00a0 mon point de vue, c&rsquo;est\u00a0 un indice tr\u00e8s fort, qu&rsquo;on n&rsquo;a pas compris l&rsquo;illusion de l&rsquo;ego; c&rsquo;est un indice tr\u00e8s, tr\u00e8s fort. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec9a2ad elementor-widget elementor-widget-heading\" data-id=\"ec9a2ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nous avons aussi discut\u00e9 dans le pass\u00e9 que il y \u00e0 certains informations,  connaissance qui se comprennent premi\u00e8rement  cognitivement, et apr\u00e8s ils prennent un peu de  temps o\u00f9 beaucoup de temps pour s'int\u00e9grer;  et que cette compr\u00e9hension de l'illusion du libre arbitre et de l'ego ca en fait partie.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32f2b1e elementor-widget elementor-widget-text-editor\" data-id=\"32f2b1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L\u00e0 je suis pas sp\u00e9cialiste, je suis pas un sp\u00e9cialiste du cerveau, donc faudrait\u00a0 voir avec des\u00a0 neuroscientifiques, l\u00e0 pour \u00a0 \u00eatre s\u00fbr, mais effectivement\u00a0 d&rsquo;apr\u00e8s mon exp\u00e9rience personnelle, entre comprendre\u00a0 cognitivement quelque\u00a0 chose, c&rsquo;est \u00e0 dire on arrive \u00e0 comprendre une th\u00e9orie, je sais pas,\u00a0 la th\u00e9orie de la relativit\u00e9 \u00a0 par exemple, o\u00f9 on \u00a0 arrive \u00e0 comprendre ce ph\u00e9nom\u00e8ne de l&rsquo;illusion\u00a0 de l&rsquo;ego, on arrive \u00e0 le\u00a0 comprendre, quelqu&rsquo;un nous \u00a0 l&rsquo;explique: \u00ab\u00a0Ah, ah, j&rsquo;ai compris!\u00a0\u00bb; mais entre le fait de le comprendre de cette \u00a0 fa\u00e7on cognitivement, et de bien l&rsquo;int\u00e9grer dans toutes les facettes\u00a0 de sa repr\u00e9sentation du monde, \u00e7a y il\u00a0 peut s&rsquo;\u00e9couler du temps beaucoup de temps \u00a0 des ann\u00e9es, peut-\u00eatre \u00a0 m\u00eame, toujours. C&rsquo;est effectivement c&rsquo;est \u00a0 toi d&rsquo;ailleurs qui au d\u00e9but m&rsquo;a sensibilis\u00e9\u00a0 \u00e0 cet aspect des choses quand tu m&rsquo;as parler \u00a0 d&rsquo;int\u00e9gration de la compr\u00e9hension des l&rsquo;illusion\u00a0 d&rsquo;ego, je pense que c&rsquo;est\u00a0 toi qui m&rsquo;en a parl\u00e9 \u00a0 le premier, je ne sais plus bien. Effectivement on peut comprendre le ph\u00e9nom\u00e8ne de l&rsquo;illusion \u00a0 de l&rsquo;ego si quelqu&rsquo;un nous\u00a0 l&rsquo;expliquent, mais \u00e7a\u00a0 va \u00eatre juste une petite\u00a0 partie de notre cerveau \u00a0 qu&rsquo;on a cette compr\u00e9hension et en fait \u00e7a va\u00a0 \u00eatre du temps au fil des jours des mois pour \u00a0 petit \u00e0 petit comprend toutes les implications,\u00a0 et par exemple on va se mettre \u00e0 comprendre \u00a0 au bout d&rsquo;un certain temps, qu&rsquo; on a plein de\u00a0 croyance associ\u00e9s mais au d\u00e9but on se rend \u00a0 pas compte que ce sont des\u00a0 croyances associ\u00e9es, on\u00a0 on va s&rsquo;en rendre compte petit \u00e0 petit. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-048cb1b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"048cb1b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bdce07 elementor-widget elementor-widget-toggle\" data-id=\"4bdce07\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7951\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7951\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Transcription int\u00e9grale<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7951\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7951\"><p><span style=\"font-weight: 400;\">Exactement \u00e0 ce que je m&rsquo;attends. Donc ce qui me perplexe derni\u00e8rement.. Avant de commencer, lorsque\u00a0 nous communiquons dans un certain langage \u00a0 comme le fran\u00e7ais nous sommes limit\u00e9s par deux\u00a0 choses au minimum. Les concepts \u00a0 que nous avons,\u00a0 la capacit\u00e9 de s&rsquo;exprimer \u00a0 avec la langue fran\u00e7aise, les concepts sont \u00a0 limit\u00e9es par la linguistique de la langue fran\u00e7aise elle-m\u00eame et de plus par nos compr\u00e9hension de certains concepts. Donc si j&rsquo;utilise des concepts tr\u00e8s complexes\u00a0 comme le Bouddha, et bien moi j&rsquo;ai une compr\u00e9hension \u00a0 et vous vous en avez une autre. D&rsquo;abord\u00a0 ce que je vous proposerai \u00a0 c&rsquo;est que de temps en temps on prend le temps d&rsquo;arr\u00eater et lorsque\u00a0 nous avons un terme complexe, une m\u00e9taphore, o\u00f9 de nous se doute que peut-\u00eatre qu&rsquo;on\u00a0 n&rsquo;a pas la m\u00eame compr\u00e9hension qu&rsquo;on \u00a0 arr\u00eate qui conte la d\u00e9finisse, que\u00a0 vous me dites que vous \u00eates ce que \u00a0 c&rsquo;est pour vous et c&rsquo;est que\u00a0 c&rsquo;est pour moi. Comme \u00e7a on arrive \u00e0\u00a0 aligner le terme lui-m\u00eame, comme \u00e7a on va\u00a0 pouvoir bien s&rsquo;entendre. Bon. Ceci \u00e9tant dit, moi je suis int\u00e9ress\u00e9 par la dissolution de l&rsquo;illusion de l&rsquo;ego. par tous les \u00eatres sentients qui ont la capacit\u00e9\u00a0 de le faire, et dans le temps \u00a0 augmenter le nombre \u00a0 d&rsquo;\u00eatres sentients qui ont la \u00a0 capacit\u00e9 de le faire. Et\u00a0 peut-\u00eatre que l&rsquo;on peut \u00a0 commencer par la d\u00e9finition de la dissolution de l&rsquo;illusion de l&rsquo;ego. Qu&rsquo;est-ce \u00a0 que ceux-ci vous dire pour vous? OK, non, \u00a0 j&rsquo;utilise un peu ce qu&rsquo;est ce qui est ce\u00a0 qui est dit par d&rsquo;autres notamment, par les \u00a0 bouddhistes. Donc l&rsquo;id\u00e9e\u00a0 centrale du bouddhisme, que\u00a0 je reprends, c&rsquo;est qu&rsquo; instinctivement on a\u00a0 le sentiment d&rsquo;\u00eatre soi. D&rsquo;avoir un ego, c&rsquo;est-\u00e0\u00a0 -dire, d&rsquo;\u00eatre une entit\u00e9 la m\u00eame et diff\u00e9rente\u00a0 \u00a0 des autres, et m\u00eame la m\u00eame entit\u00e9 au fil du\u00a0 temps. Je suis n\u00e9 Jean-Christophe \u00a0 un jour et\u00a0 je mourrai Jean-Christophe\u00a0 \u00e0 cent ans. Donc il y a cette id\u00e9e d&rsquo;\u00eatre soi \u00a0 et diff\u00e9rent des autres, voil\u00e0. Donc \u00e7a c&rsquo;est le sentiment d&rsquo;avoir un \u00e9go, on va\u00a0 qualifier \u00e7a comme \u00e7a, l&rsquo;impression d&rsquo;avoir \u00a0 un ego, et ce que ce qu&rsquo;a dit le bouddhisme c&rsquo;est que c&rsquo;est une illusion, cette impression \u00a0 c&rsquo;est une illusion mentale. Donc pour revenir \u00e0 ta\u00a0 question: \u00ab\u00a0Qu&rsquo;est-ce que\u00a0 dissoudre l&rsquo;illusion d&rsquo;ego?\u00a0\u00bb,\u00a0 et bien c&rsquo;est c&rsquo;est comprendre\u00a0 la nature de cette \u00a0 illusion mentale et r\u00e9ussir petit \u00e0 petit \u00e0 la\u00a0 faire reculer. Alors de mon \u00a0 point de vue je ne sais\u00a0 pas si on peut la faire totalement reculer\u00a0 sans devenir totalement schizophr\u00e8ne, d&rsquo;avoir \u00a0 un gros probl\u00e8me de d\u00e9personnalisation, \u00e7a j&rsquo;en sais rien, mais ce que je\u00a0 sais c&rsquo;est qu&rsquo;on peut\u00a0 faire reculer quand m\u00eame de plus en plus au fil\u00a0 des ann\u00e9es cette illusion, voil\u00e0. Mais elle reste l\u00e0 dans mon cas, dans tous les cas elle reste\u00a0 l\u00e0. Dans mon cas, en tous les cas, elle est\u00a0 constamment l\u00e0, simplement je peux\u00a0 la mettre un petit peu \u00e0 distance, je peux\u00a0 je peux faire malgr\u00e9 cette illusion, voil\u00e0. Vous m&rsquo;avez aussi dit que cette illusion est tr\u00e8s li\u00e9e, sinon \u00a0 compl\u00e8tement identique \u00e0 l&rsquo;illusion\u00a0 du libre arbitre. Est-ce correct? Alors elle est extr\u00eamement\u00a0 li\u00e9e, c&rsquo;est pas \u00e9quivalent, \u00a0 mais c&rsquo;est extr\u00eamement li\u00e9e.\u00a0 Euh, je veux dire que si quelqu&rsquo;un croit au libre arbitre, alors on\u00a0 peut \u00eatre s\u00fbr qu&rsquo;ils croient \u00e0 l&rsquo;ego, parce \u00a0 que pour qu&rsquo;il y est libre arbitre, il faudrait\u00a0 qu&rsquo;il y est arbitre; donc quelqu&rsquo;un qui croit au\u00a0 libre arbitre c&rsquo;est qu&rsquo;ils croient qu&rsquo;il ya un arbitre.\u00a0 c&rsquo;est la n\u00e9go c&rsquo;est la m\u00eame chose si on croit \u00a0 qu&rsquo;un arbitre c&rsquo;est qu&rsquo;on croit qu&rsquo;un ego. Voil\u00e0, donc ce qu&rsquo;on peut dire \u00a0 c&rsquo;est que si quelqu&rsquo;un \u00a0 croit au libre arbitre \u00e7a veut dire qu&rsquo;il croit\u00a0 \u00e0 l&rsquo;ego. C&rsquo;est dans ce sens que\u00a0 les deux concepts sont intimement li\u00e9s, voil\u00e0.\u00a0 Lors d&rsquo;ailleurs, d&rsquo;ailleurs croire au libre arbitre, de\u00a0 mon point de vue, c&rsquo;est\u00a0 un indice tr\u00e8s fort, qu&rsquo;on n&rsquo;a pas compris l&rsquo;illusion de l&rsquo;ego; c&rsquo;est un indice tr\u00e8s, tr\u00e8s fort. Ce qui est\u00a0 curieux d&rsquo;ailleurs c&rsquo;est que Matthieu Ricard pour des raisons que je ne m&rsquo;explique pas du tout, je ne comprends pas, je j&rsquo;imagine qu&rsquo;il le fait\u00a0 expr\u00e8s, mais il faut d&rsquo;abord parler avec lui, \u00a0 Matthieu Ricard comprends parfaitement illusion\u00a0 de l&rsquo;ego qui est la base et\u00a0 bouddhisme, et pourtant \u00a0 dans un livre qu&rsquo;il a co-\u00e9crit avec Wolf Singer, qui est un neurobiologiste \u00a0 allemand c\u00e9l\u00e8bre,\u00a0 Wolf Singer aussi pareil, ils ont tout un chapitre qui est\u00a0 qui explique l&rsquo;illusion de l&rsquo;ego donc ils sont tout \u00e0\u00a0 fait d&rsquo;accord l\u00e0 dessus,\u00a0 par contre, apr\u00e8s il y a un\u00a0 chapitre sur le libre arbitre\u00a0 ou Matthieu Ricard \u00a0 pr\u00e9tend qu&rsquo;il y aurait un\u00a0 libre arbitre alors que\u00a0 Wolf Singer lui, d\u00e9bats si il y a pas\u00a0 d&rsquo;ego comment \u00a0 pourrait-il y avoir un libre arbitre. Voil\u00e0\u00a0 donc \u00e7a c&rsquo;est quelque chose que je n&rsquo;explique\u00a0 pas, de la peur de Matthieu Ricard.\u00a0 Donc pour vous l&rsquo;illusion du libre arbitre est une indication que la personne croit encore dans l&rsquo;illusion de l&rsquo;ego dont ce n&rsquo;est pas quelqu&rsquo;un qui est dans le chemin de la dissolution.Nous avons aussi discut\u00e9 dans le pass\u00e9 que il y \u00e0 certains informations,\u00a0 connaissance qui se comprennent premi\u00e8rement\u00a0 cognitivement, et apr\u00e8s ils prennent un peu de\u00a0 temps o\u00f9 beaucoup de temps pour s&rsquo;int\u00e9grer;\u00a0 et que cette compr\u00e9hension de l&rsquo;illusion du libre arbitre et de l&rsquo;ego ca en fait partie. Je comprends ce que \u00e7a veut dire, les \u00a0 mots que vous venez de me dire, mais apr\u00e8s \u00e7a l&rsquo;appliquer, l&rsquo;appliquer\u00a0 pragmatiquement dans nos \u00a0 vies, \u00e7a peut prendre toute une vie o\u00f9 on va pas\u00a0 y arriver jusqu&rsquo;a la fin de la vie.\u00a0 L\u00e0 je suis pas sp\u00e9cialiste, je suis pas un sp\u00e9cialiste du cerveau, donc faudrait\u00a0 voir avec des\u00a0 neuroscientifiques, l\u00e0 pour \u00a0 \u00eatre s\u00fbr, mais effectivement\u00a0 d&rsquo;apr\u00e8s mon exp\u00e9rience personnelle, entre comprendre\u00a0 cognitivement quelque\u00a0 chose, c&rsquo;est \u00e0 dire on arrive \u00e0 comprendre une th\u00e9orie, je sais pas,\u00a0 la th\u00e9orie de la relativit\u00e9 \u00a0 par exemple, o\u00f9 on \u00a0 arrive \u00e0 comprendre ce ph\u00e9nom\u00e8ne de l&rsquo;illusion\u00a0 de l&rsquo;ego, on arrive \u00e0 le\u00a0 comprendre, quelqu&rsquo;un nous \u00a0 l&rsquo;explique: \u00ab\u00a0Ah, ah, j&rsquo;ai compris!\u00a0\u00bb; mais entre le fait de le comprendre de cette \u00a0 fa\u00e7on cognitivement, et de bien l&rsquo;int\u00e9grer dans toutes les facettes\u00a0 de sa repr\u00e9sentation du monde, \u00e7a y il\u00a0 peut s&rsquo;\u00e9couler du temps beaucoup de temps \u00a0 des ann\u00e9es, peut-\u00eatre \u00a0 m\u00eame, toujours. C&rsquo;est effectivement c&rsquo;est \u00a0 toi d&rsquo;ailleurs qui au d\u00e9but m&rsquo;a sensibilis\u00e9\u00a0 \u00e0 cet aspect des choses quand tu m&rsquo;as parler \u00a0 d&rsquo;int\u00e9gration de la compr\u00e9hension des l&rsquo;illusion\u00a0 d&rsquo;ego, je pense que c&rsquo;est\u00a0 toi qui m&rsquo;en a parl\u00e9 \u00a0 le premier, je ne sais plus bien. Effectivement on peut comprendre le ph\u00e9nom\u00e8ne de l&rsquo;illusion \u00a0 de l&rsquo;ego si quelqu&rsquo;un nous\u00a0 l&rsquo;expliquent, mais \u00e7a\u00a0 va \u00eatre juste une petite\u00a0 partie de notre cerveau \u00a0 qu&rsquo;on a cette compr\u00e9hension et en fait \u00e7a va\u00a0 \u00eatre du temps au fil des jours des mois pour \u00a0 petit \u00e0 petit comprend toutes les implications,\u00a0 et par exemple on va se mettre \u00e0 comprendre \u00a0 au bout d&rsquo;un certain temps, qu&rsquo; on a plein de\u00a0 croyance associ\u00e9s mais au d\u00e9but on se rend \u00a0 pas compte que ce sont des\u00a0 croyances associ\u00e9es, on\u00a0 on va s&rsquo;en rendre compte petit \u00e0 petit . Par exemple, je vais \u00a0 dire tr\u00e8s, tr\u00e8s vite. Si on regarde l&rsquo;essentiel de\u00a0 la production philosophie \u00a0 contemporaine, tous les \u00a0 grands auteurs, Peter Singer, \u00a0 les \u00e9thiciens actuels,\u00a0 on se rend compte \u00a0 qu&rsquo;ils croient tous \u00e0 l&rsquo;ego! On \u00a0 prend n&rsquo;importe quel bouquin de philosophie\u00a0 ou, ou des \u00e9thiciens de la cause animale, par \u00a0 exemple, par exemple, tous ceux qui croient \u00e0 la\u00a0 sentience, par exemple donc il ya beaucoup de gens qui sont persuad\u00e9s que la sentience c&rsquo;est autre chose\u00a0 qu&rsquo;\u00eatre sensible. Je crois que Yves Bonnardel le dit encore dans un article r\u00e9cent dans \u00a0 l&rsquo;Amorce. Mais \u00e7a \u00a0 c&rsquo;est pareil si on regarde le concept de \u00a0 sentience, \u00e7a s&rsquo;accroche \u00e0 l&rsquo;id\u00e9e qu&rsquo;il ya\u00a0 un ego, par exemple que ce seront les \u00eatres \u00a0 du projet de toute une vie ou alors quand on\u00a0 voit des philosophes qui parle d&rsquo;int\u00e9r\u00eats l&rsquo;un \u00a0 \u00eatre comme si l&rsquo;\u00eatre il existait! Donc d\u00e8s qu&rsquo;on\u00a0 est un petit peu sensibilis\u00e9s et qu&rsquo;on comprend \u00a0 en profondeur l&rsquo;illusion de l&rsquo;ego on se rend compte\u00a0 que quasiment 99 % de la production philosophie \u00a0 contemporaine est fausse! Ce qui est incroyable\u00a0 c&rsquo;est ce qui est vraiment incroyable! Et c&rsquo;est \u00a0 d&rsquo;autant plus incroyable que les philosophes\u00a0 occidentaux contemporains savent, connaissent ce \u00a0 probl\u00e8me de l&rsquo;illusion de l&rsquo;ego qui porte \u00a0 un autre nom en philosophie \u00a0 mais habituellement on appelle \u00e7a \u00a0 le probl\u00e8me de l&rsquo;identit\u00e9 personnelle a travers le\u00a0 temps: c&rsquo;est comme \u00e7a qu&rsquo;on\u00a0 en parle en philosophie \u00a0 depuis les grecs depuis\u00a0 l&rsquo;antiquit\u00e9 c&rsquo;est comme \u00e7a\u00a0 qu&rsquo;on en parle et tous les\u00a0 philosophes occidentaux sont form\u00e9s \u00e0 \u00e7a. Tient pendant leurs \u00e9tudes on\u00a0 leur a appris qu&rsquo; il n&rsquo;y avait pas d&rsquo;identit\u00e9 de \u00a0 la personne au fil du temps, ce qui revient \u00e0 peu\u00a0 pr\u00e8s au m\u00eame que de dire \u00a0 qu&rsquo;il ya une illusion de \u00a0 l&rsquo;ego. Donc ils sont form\u00e9s \u00e0 \u00e7a, ils le savent,\u00a0 mais de fa\u00e7on assez\u00a0 inexplicable d\u00e8s qu&rsquo; ils passent \u00e0 un autre sujet, ils ont compl\u00e8tement oubli\u00e9,\u00a0 ils ont compl\u00e8tement oubli\u00e9, donc ils vous expliquent \u00a0 qu&rsquo; il y a des \u00eatres qui ont des int\u00e9r\u00eats. On se dit, c&rsquo;est l&rsquo;\u00eatre \u00e0 l&rsquo;instant \u00ab\u00a0t\u00a0\u00bb ou l&rsquo;\u00eatre \u00a0 une heure d&rsquo;apr\u00e8s, parce qu&rsquo;ils peuvent avoir des\u00a0 int\u00e9r\u00eats diff\u00e9rents. Donc\u00a0 voil\u00e0, c&rsquo;est juste une petite \u00a0 illustration qui montre \u00e0 quel point m\u00eame pour\u00a0 des professionnels, les \u00e9lites intellectuelles \u00a0 de notre monde, n&rsquo;arrive pas \u00e0 int\u00e9grer ce\u00a0 savoir. C&rsquo;est fou. C&rsquo;est compl\u00e8tement fou!\u00a0\u00a0<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jean-Christophe a d\u00e9cid\u00e9 tr\u00e8s t\u00f4t de consacrer sa vie \u00e0 l\u2019organisation de la cr\u00e9ation d\u2019un plus grand bonheur dans le monde. Dans ce but, il a d\u2019abord suivi une formation d\u2019\u00e9conomiste et est devenu un strat\u00e8ge cl\u00e9 en charge des grands projets de la plus grande corporation publique fran\u00e7aise, La Poste. Il a \u00e9crit \u00ab\u00a0Na\u00eetre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,1],"tags":[],"class_list":["post-890","post","type-post","status-publish","format-standard","hentry","category-articles-fr","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dissolution de l&#039;illusion de l&#039;ego - Jean Christophe Lurenbaum ~ Sorin Ionescu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dissolution de l&#039;illusion de l&#039;ego - Jean Christophe Lurenbaum ~ Sorin Ionescu\" \/>\n<meta property=\"og:description\" content=\"Jean-Christophe a d\u00e9cid\u00e9 tr\u00e8s t\u00f4t de consacrer sa vie \u00e0 l\u2019organisation de la cr\u00e9ation d\u2019un plus grand bonheur dans le monde. Dans ce but, il a d\u2019abord suivi une formation d\u2019\u00e9conomiste et est devenu un strat\u00e8ge cl\u00e9 en charge des grands projets de la plus grande corporation publique fran\u00e7aise, La Poste. Il a \u00e9crit \u00ab\u00a0Na\u00eetre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorin Ionescu\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-27T03:39:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-27T03:39:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg\" \/>\n<meta name=\"author\" content=\"Sorin Ionescu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorin Ionescu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/\"},\"author\":{\"name\":\"Sorin Ionescu\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"headline\":\"Dissolution de l&rsquo;illusion de l&rsquo;ego &#8211; Jean Christophe Lurenbaum\",\"datePublished\":\"2022-02-27T03:39:02+00:00\",\"dateModified\":\"2022-02-27T03:39:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/\"},\"wordCount\":2886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/JCL_new-adjusted-300x300-1.jpeg\",\"articleSection\":[\"Articles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/\",\"name\":\"Dissolution de l'illusion de l'ego - Jean Christophe Lurenbaum ~ Sorin Ionescu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/JCL_new-adjusted-300x300-1.jpeg\",\"datePublished\":\"2022-02-27T03:39:02+00:00\",\"dateModified\":\"2022-02-27T03:39:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/JCL_new-adjusted-300x300-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/JCL_new-adjusted-300x300-1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/articles\\\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sorinionescu.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dissolution de l&rsquo;illusion de l&rsquo;ego &#8211; Jean Christophe Lurenbaum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/\",\"name\":\"Sorin Ionescu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sorinionescu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\",\"name\":\"Sorin Ionescu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"width\":126,\"height\":119,\"caption\":\"Sorin Ionescu\"},\"logo\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\"},\"sameAs\":[\"https:\\\/\\\/sorinionescu.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dissolution de l'illusion de l'ego - Jean Christophe Lurenbaum ~ Sorin Ionescu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/","og_locale":"fr_FR","og_type":"article","og_title":"Dissolution de l'illusion de l'ego - Jean Christophe Lurenbaum ~ Sorin Ionescu","og_description":"Jean-Christophe a d\u00e9cid\u00e9 tr\u00e8s t\u00f4t de consacrer sa vie \u00e0 l\u2019organisation de la cr\u00e9ation d\u2019un plus grand bonheur dans le monde. Dans ce but, il a d\u2019abord suivi une formation d\u2019\u00e9conomiste et est devenu un strat\u00e8ge cl\u00e9 en charge des grands projets de la plus grande corporation publique fran\u00e7aise, La Poste. Il a \u00e9crit \u00ab\u00a0Na\u00eetre [&hellip;]","og_url":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/","og_site_name":"Sorin Ionescu","article_published_time":"2022-02-27T03:39:02+00:00","article_modified_time":"2022-02-27T03:39:07+00:00","og_image":[{"url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg","type":"","width":"","height":""}],"author":"Sorin Ionescu","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorin Ionescu","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#article","isPartOf":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/"},"author":{"name":"Sorin Ionescu","@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"headline":"Dissolution de l&rsquo;illusion de l&rsquo;ego &#8211; Jean Christophe Lurenbaum","datePublished":"2022-02-27T03:39:02+00:00","dateModified":"2022-02-27T03:39:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/"},"wordCount":2886,"commentCount":0,"publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"image":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg","articleSection":["Articles","Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/","url":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/","name":"Dissolution de l'illusion de l'ego - Jean Christophe Lurenbaum ~ Sorin Ionescu","isPartOf":{"@id":"https:\/\/sorinionescu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#primaryimage"},"image":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg","datePublished":"2022-02-27T03:39:02+00:00","dateModified":"2022-02-27T03:39:07+00:00","breadcrumb":{"@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#primaryimage","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2022\/02\/JCL_new-adjusted-300x300-1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/sorinionescu.org\/articles\/dissolution-of-the-illusion-of-the-ego-jean-christophe-lurenbaum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sorinionescu.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Dissolution de l&rsquo;illusion de l&rsquo;ego &#8211; Jean Christophe Lurenbaum"}]},{"@type":"WebSite","@id":"https:\/\/sorinionescu.org\/#website","url":"https:\/\/sorinionescu.org\/","name":"Sorin Ionescu","description":"","publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sorinionescu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae","name":"Sorin Ionescu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","width":126,"height":119,"caption":"Sorin Ionescu"},"logo":{"@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png"},"sameAs":["https:\/\/sorinionescu.org"]}]}},"_links":{"self":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":3,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":894,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/posts\/890\/revisions\/894"}],"wp:attachment":[{"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sorinionescu.org\/fr\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}