{"id":840,"date":"2021-04-10T07:12:30","date_gmt":"2021-04-10T11:12:30","guid":{"rendered":"https:\/\/sorinionescu.org\/non-categorizzato\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/"},"modified":"2021-04-10T07:28:42","modified_gmt":"2021-04-10T11:28:42","slug":"governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio","status":"publish","type":"post","link":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/","title":{"rendered":"Governance globale e movimenti sociali &#8211; dialogo con Roberto Savio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"840\" class=\"elementor elementor-840 elementor-818\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2728fe4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2728fe4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf90b40\" data-id=\"bf90b40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e2d0e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e2d0e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a955904\" data-id=\"a955904\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d42d2de elementor-widget elementor-widget-image\" data-id=\"d42d2de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\" class=\"attachment-large size-large wp-image-798\" alt=\"\" srcset=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png 640w, https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance.-300x199.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2bec1aa\" data-id=\"2bec1aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2a1da5 elementor-widget elementor-widget-text-editor\" data-id=\"d2a1da5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Roberto_Savio\">Roberto Savio<\/a>\u00a0\u00e8 giornalista, esperto di comunicazione, commentatore politico, attivista per la giustizia sociale e climatica e avvocato della governance globale. \u00c8 fondatore e presidente emerito dell\u2019agenzia di stampa\u00a0<a href=\"http:\/\/www.ips.org\/\">Inter Press Service (IPS)<\/a>\u00a0ed editore di Other News.<\/p>\n<p>Ho avuto la fortuna di incontrare Roberto attraverso il mio attivismo, e quando ho iniziato a interessarmi la governance globale e il ruolo dei movimenti sociali, gli ho chiesto un dialogo sull\u2019argomento. La sua competenza e la sua saggezza in materia sono ampie, e gli sono molto grato per il suo tempo e per il dialogo che segue.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-90bfd77 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"90bfd77\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38b2261 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38b2261\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b386ea\" data-id=\"1b386ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99ada6d elementor-widget elementor-widget-heading\" data-id=\"99ada6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parte 1. Come si organizza la governance nella societ\u00e0 civile.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62991c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62991c8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86054ff\" data-id=\"86054ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544deb0 elementor-widget elementor-widget-video\" data-id=\"544deb0\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/LQ4bk87fnqU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bd3c48b\" data-id=\"bd3c48b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-716b70d elementor-widget elementor-widget-text-editor\" data-id=\"716b70d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roberto Savio discute il suo punto di vista sulla governance e i problemi che percepisce con l&#8217;inefficacia dei movimenti sociali nell&#8217;implementare un efficace cambiamento sociale a causa della mancanza di struttura organizzativa e di un&#8217;adeguata interazione con i sistemi di governo attuali.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21903c3 elementor-blockquote--skin-quotation elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"21903c3\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t<p>Tutti questi movimenti si sono affievoliti e sono scomparsi, perch\u00e9 non si strutturano. In altre parole non prendono la governabilit\u00e0 strumentale, perch\u00e9 pensano che la governabilit\u00e0 venga dal campo politico ed \u00e8 una trappola.<\/p>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Roberto Savio<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-641e7d1 elementor-widget elementor-widget-toggle\" data-id=\"641e7d1\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1041\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Leggi la trascrizione completa<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1041\"><p>Quindi lasciatemi dire che c&#8217;\u00e8 una questione molto molto importante e cruciale, che non trova soluzione. &#8220;Come si organizza la governance nella societ\u00e0 civile&#8221;.<\/p>\n<p>Questa \u00e8 una questione molto centrale, e purtroppo \u00e8 una questione dove c&#8217;\u00e8 un dibattito in corso, ma praticamente non vedo nessuna soluzione nel breve tempo. La societ\u00e0 civile \u00e8 l&#8217;insieme delle persone che si uniscono su diverse questioni in cui condividono una visione o una preoccupazione. Avete persone che si uniscono sulla questione del clima, avete persone che si uniscono sulla questione dei diritti umani, avete persone che si uniscono sulla questione delle disuguaglianze, avete persone che si uniscono sulla discriminazione razziale, sulla questione dei diritti delle donne, e cos\u00ec via.<\/p>\n<p>Tutte queste organizzazioni formano la societ\u00e0 civile. Queste organizzazioni, in generale, non sono strutturate, sono persone che si mettono insieme e lavorano insieme, ma senza una struttura giuridica o qualcosa del genere. Perch\u00e9, a causa della cultura dopo il maggio 68. Avete presente il maggio 68 francese? Ok, dopo quel maggio 68 francese, un&#8217;ondata ha attraversato i giovani, e la gente ha rifiutato l&#8217;autorit\u00e0, le norme, i regolamenti. Il risultato: faccio l&#8217;esempio del Forum Sociale Mondiale, che \u00e8 uno dei pi\u00f9 grandi raduni di persone.<\/p>\n<p>Abbiamo ad ogni riunione circa 100 000 persone, che non \u00e8 una cosa da poco. Ma lo statuto che avevamo per gestire il Forum Sociale Mondiale era basato su tre idee.<\/p>\n<p>Una: non vogliamo cadere nella trappola di un partito politico, perch\u00e9 un partito politico \u00e8 un sistema burocratico di potere. Non abbiamo intenzione di caderci. Quindi non ci saranno partiti politici all&#8217;interno del Forum Sociale Mondiale, progressisti o no, non importa. Non vogliamo nessun partito politico.<br \/>\nDue: siamo tutti uguali. Nessuno deve parlare a nome dell&#8217;altro. Quindi non possiamo eleggere un consiglio, non possiamo eleggere nessuna struttura.<br \/>\nTre, quindi dobbiamo prendere le nostre decisioni per consenso, significa per il cento per cento di unanimit\u00e0.<br \/>\nOra, se guardate tutti i grandi movimenti del passato, di Occupy Wall Street, di uno qualsiasi di questi movimenti che sono venuti fuori fino ad oggi, con le donne, il movimento delle donne, Me Too, o il movimento sul clima, non si sono mai strutturati. Erano solo movimenti di persone che si riunivano insieme. Il risultato \u00e8 che tutti questi movimenti non sono mai diventati qualcosa di duraturo, perch\u00e9 sono stati fatti sulla spinta dei sentimenti, dell&#8217;azione, ma non si sono mai strutturati. Occupy Wall Street, ancora una volta tutti erano uguali, le decisioni venivano prese all&#8217;unanimit\u00e0 e cos\u00ec via. Il risultato \u00e8 che Occupy Wall Street si \u00e8 lentamente affievolito ed \u00e8 scomparso.<\/p>\n<p>Tutti questi movimenti si sono affievoliti e sono scomparsi, perch\u00e9 non si strutturano. In altre parole non prendono la governabilit\u00e0 strumentale, perch\u00e9 pensano che la governabilit\u00e0 venga dal campo politico ed \u00e8 una trappola. E tutti vogliono essere uguali e cos\u00ec via.<\/p>\n<p>Il risultato \u00e8 che, secondo me, abbiamo un problema che non ha soluzione. Che tutto quello che facciamo sulle questioni globali \u00e8 perch\u00e9 vogliamo cambiare le leggi e questo in pratica sulla questione che ci interessa. Sul clima vogliamo lottare per una politica climatica diversa. Ora chi decide quale cambiamento fare sul clima? I governi, o meglio, i parlamenti, in altre parole le forze politiche. Poich\u00e9 non vogliamo avere alcuna relazione con le forze politiche, tutte le nostre lotte, tutti i nostri dibattiti, tutte le nostre idee non entrano nel sistema. E se non entrano nel sistema non cambiano il sistema.<\/p>\n<p>Greta Thunberg era una portavoce del movimento perch\u00e9 ha iniziato il movimento e ha preso quel posto, ma non \u00e8 mai stata eletta portavoce del movimento per il clima. Nessuno seleziona le portavoce di Me Too. Nessuno selezioner\u00e0 la persona spock del Black Lives Matter. Sono state le persone che hanno iniziato a parlare e sono diventate portavoce de facto.<\/p>\n<p>Ma il problema \u00e8 che queste cose sono estremamente fragili, e non entrano nel sistema perch\u00e9 hanno una natura, un linguaggio e una formula diversi. Cos\u00ec tutto lo sforzo che la societ\u00e0 civile ha fatto negli ultimi&#8230; da quando \u00e8 nata negli anni &#8217;80, beh fondamentalmente non ha portato molti cambiamenti, perch\u00e9 i partiti politici li ignorano, il parlamento li ignora, e cos\u00ec non si va molto lontano. Se ci fossimo strutturati in movimenti con risoluzioni con un&#8217;azione che andasse direttamente nel sistema, avremmo potuto influenzare il sistema molto, molto di pi\u00f9. Ma nella societ\u00e0 civile non vogliamo essere come il sistema.<\/p>\n<p>Quindi c&#8217;\u00e8 un problema che non ha soluzione. Se non troviamo un modo per diventare capaci di comunicare nel sistema, ma parliamo solo nelle strade, beh le forze politiche non hanno problemi ad ignorarci. E questa \u00e8 una questione generale.<\/p>\n<p>I giovani, oggi, hanno poca importanza nel sistema. Perch\u00e9 sono meno, nei paesi industrializzati, dei vecchi. I vecchi hanno una serie di agevolazioni, per esempio in Italia andiamo al cinema con uno sconto, andiamo al museo, gratis. Abbiamo una serie di cose, la terza generazione, la terza et\u00e0, una serie di vantaggi che non viene data ai giovani, e le leggi sono sempre pi\u00f9 orientate agli anziani perch\u00e9 votano, rispetto ai giovani, che non votano. Questo \u00e8 qualcosa che sta accadendo ovunque. Non ci sarebbe stata la Brexit, se i giovani avessero votato, perch\u00e9 erano tutti contro la Brexit, ma non hanno votato, cos\u00ec \u00e8 uscita la Brexit. E poi avete avuto questa manifestazione nelle strade di giovani che protestavano.<\/p>\n<p>Quindi c&#8217;\u00e8 un problema: o troviamo un modo di governare che sia in grado di rappresentarci, ma anche di avere un impatto nel sistema, o il sistema ci ignorer\u00e0 completamente e noi continueremo.<\/p>\n<p>C&#8217;\u00e8 stata una dichiarazione molto famosa di Soros al secondo Forum Sociale Mondiale. Soros disse: &#8220;Ragazzi, siamo molto contenti che vi impegnate nella societ\u00e0 civile, siamo contenti che aiutate tutte le persone in ospedale, tenete aperti i musei locali con i volontari, fate un sacco di lavoro, che in un certo senso rende il sistema statale pi\u00f9 capace di funzionare. Perch\u00e9 voi prendete le cose che lo stato dovrebbe fare, le deludono, e voi intervenite in modo volontario per sviluppare le cose, quindi siamo molto contenti. E voi siete molto impegnati in quello che fate e noi facciamo quello che facciamo, quindi vi ringrazio molto. Perch\u00e9 in effetti ci state aiutando&#8221;. Ho trovato quella dichiarazione estremamente cinica, ma una dichiarazione molto buona, perch\u00e9 se sei un multimilionario, beh le persone che vanno a fare volontariato, fantastico! Riducono l&#8217;inefficienza del sistema e non fanno cambiare nulla. Grazie.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfdc70d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfdc70d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d9cc00\" data-id=\"3d9cc00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44ac341 elementor-widget elementor-widget-heading\" data-id=\"44ac341\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sorin:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f2ccde elementor-widget elementor-widget-text-editor\" data-id=\"5f2ccde\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono stato coinvolto nei movimenti sociali per un po&#8217;, e c&#8217;\u00e8 un nuovo tipo di movimento sociale che sta emergendo, forse Extinction Rebellion, Animal Rebellion di cui faccio parte, che potrebbe essere consapevole di questo problema. Siamo consapevoli del fatto che un movimento \u00e8 come, diciamo, un tavolo che sta su quattro gambe. Una gamba \u00e8 la <strong>strategia<\/strong>, una gamba \u00e8 la sua <strong>storia<\/strong>, una gamba \u00e8 la <strong>cultura<\/strong>, e una gamba \u00e8 la <strong>struttura<\/strong> emergente della <strong>governance<\/strong>.<\/p>\n<p>Per un&#8217;altra analogia, possiamo paragonare un movimento sociale a un organismo vivente,<\/p>\n<ul>\n<li>Potrebbe aver bisogno di una direzione e di un modo per arrivare da qualche parte e muoversi nel mondo, questa potrebbe essere la <strong>strategia<\/strong>.<\/li>\n<li>Potrebbe aver bisogno di un modo per interagire con il mondo, come interagiamo oggi per discutere, questa \u00e8 la <strong>storia<\/strong> che mette avanti, o come inquadra la narrazione.<\/li>\n<li>Avrebbe bisogno di un modo per comunicare internamente, che \u00e8 la sua <strong>cultura<\/strong>, che \u00e8 come il segnale chimico avviene localmente tra le cellule, come il sistema nervoso trasmette le informazioni, come il sangue porta i nutrienti.<\/li>\n<li>Infine, potrebbe aver bisogno della parte di cui stiamo discutendo qui, che \u00e8 la <strong>struttura<\/strong>. Come \u00e8 strutturato l&#8217;organismo in organi e qual \u00e8 lo scheletro dell&#8217;organismo, e il governo \u00e8 legato a tutto questo perch\u00e9 \u00e8 il pilastro su cui si decide la struttura.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d09ad1 elementor-widget elementor-widget-heading\" data-id=\"7d09ad1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parte 2. Il consenso \u00e8 antidemocratico? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35e98ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35e98ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e146b35\" data-id=\"e146b35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79bb435 elementor-widget elementor-widget-video\" data-id=\"79bb435\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/NNx4iQCjn3A&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-881dee2\" data-id=\"881dee2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e467cc2 elementor-widget elementor-widget-text-editor\" data-id=\"e467cc2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roberto Savio esprime il suo punto di vista secondo il quale il governo al 100% del consenso non \u00e8 solo inefficiente, ma forse antidemocratico.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-974fe5f elementor-blockquote--skin-quotation elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"974fe5f\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t<p>Ora \u00e8 totalmente ingenuo e assurdo pensare che il sistema non sia basato sul potere e sui gruppi di potere. Assurdo pensare che i partiti politici non rispondano alle lobby, alle persone con soldi, che finanziano le elezioni. \u00c8 totalmente assurdo ignorare che la disuguaglianza viene da persone che hanno soldi molto al di l\u00e0 delle loro necessit\u00e0, ma che non sono disposte a dare un centesimo dei loro soldi.<\/p>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Roberto Savio<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b08a9f8 elementor-widget elementor-widget-toggle\" data-id=\"b08a9f8\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Leggi la trascrizione completa<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1851\"><p>Prima parlava del Forum Sociale Mondiale, dove ha detto che le decisioni vengono prese per consenso, dove tutti devono essere d&#8217;accordo. Beh, io sostengo che quando facciamo cose del genere pu\u00f2 diventare inefficace, perch\u00e9 ci vuole molto tempo perch\u00e9 tutti siano d&#8217;accordo. contro.<\/p>\n<p>Non solo, non solo, Sorin, ma \u00e8 antidemocratico. Perch\u00e9 se hai una riunione di 100 persone e una non \u00e8 d&#8217;accordo non puoi rendere democratico un accordo.<\/p>\n<p>Esattamente!<\/p>\n<p>Io dico: facciamo un quorum dell&#8217;80 per cento, 85 per cento 90, ma non si pu\u00f2 avere un quorum del 100 per cento. Se abbiamo paura di dividere il movimento, che era una delle preoccupazioni di Occupy Wall Street, non volevano istituire nessun portavoce, niente, perch\u00e9 dicevano che sono persone diverse, priorit\u00e0 diverse, sensibilit\u00e0 diverse, se eleggiamo qualcuno divideremo il movimento. Ok, io dico: facciamo un quorum del 90 per cento in modo da essere sicuri che questi rappresentino il 90 per cento della gente. Ma perch\u00e9 dovrebbero rappresentare il 100%? Chi ha detto che il movimento deve rappresentare il 100% del popolo? Devono rappresentare una maggioranza molto molto ampia, ma se hanno poche persone che non sono d&#8217;accordo, che importa? Voglio dire che questo non \u00e8 democratico.<\/p>\n<p>Quindi vedete questo \u00e8 quello che io vedo come un problema e poi vi faccio un altro esempio. Siccome nessuno pu\u00f2 parlare a nome del Forum Sociale Mondiale, perch\u00e9 questo significa che qualcuno viene eletto come portavoce, il Forum Sociale Mondiale \u00e8 scomparso dai media. Perch\u00e9 non faremo mai nessuna dichiarazione su niente. Assurdo perch\u00e9 non vedo chi far\u00e0 una dichiarazione contro la pace, non vedo chi far\u00e0 una dichiarazione contro il cambiamento climatico.<\/p>\n<p>Voglio dire che ci sono questioni su cui il movimento \u00e8 unito e poi si pu\u00f2 avere magari nel movimento Me Too alcune femministe che vedono le cose in modo diverso da altre femministe. Ma non ha senso che il movimento Me Too non abbia questa struttura organizzata su cui possono andare a parlare al congresso degli Stati Uniti e dire: Noi vogliamo questo, perch\u00e9 rappresentiamo questo problema. E Me Too, o Black Lives Matter, non c&#8217;\u00e8 una struttura per negoziare con il potere.<\/p>\n<p>Ora \u00e8 totalmente ingenuo e assurdo pensare che il sistema non sia basato sul potere e sui gruppi di potere. Assurdo pensare che i partiti politici non rispondano ai lobbisti, alle persone con soldi, che finanziano le elezioni. Assolutamente assurdo ignorare che la disuguaglianza viene da persone che hanno soldi molto al di l\u00e0 delle loro necessit\u00e0, ma che non sono disposte a dare un centesimo dei loro soldi. A meno che per la filantropia che \u00e8 diverso, perch\u00e9 allora non paghi le tasse, metti i tuoi soldi in una filantropia, non paghi le tasse su quei soldi e ottieni lo status.<\/p>\n<p>Quindi non so, trovo che si sia raggiunto un punto in cui si comincia a discutere, ma poi la gente ti accusa di leninismo e io vengo accusato di leninismo perch\u00e9 voglio organizzare qualche struttura. Ora direi che Lenin non era particolarmente importante nella struttura. Era importante nell&#8217;obiettivo della rivoluzione e della dittatura organizzata del proletariato per raggiungere l&#8217;obiettivo. Ma non fu qualcuno che organizz\u00f2 una dittatura del proletariato per la dittatura del proletariato. In altre parole, l&#8217;organizzazione non era il suo obiettivo principale. Il suo obiettivo principale era un&#8217;azione politica.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93951f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93951f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0369b8e\" data-id=\"0369b8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c220a2a elementor-widget elementor-widget-heading\" data-id=\"c220a2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sorin:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77a3e56 elementor-widget elementor-widget-text-editor\" data-id=\"77a3e56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direi che sono in alcuni movimenti e vedo una certa struttura e potrebbe esserci una differenza tra non avere una struttura e non avere una struttura gerarchica. Alcuni movimenti hanno una struttura autogestita, auto-organizzata, con regole chiare, struttura chiara, modi chiari di prendere decisioni.<\/p>\n<p>E per commentare i problemi senza soluzione&#8230; Ho molta speranza e fede. C&#8217;\u00e8 una piccola metafora, un&#8217;analogia che ho sentito molte volte. Se guardate un bruco, mangia la foglia su cui si trova, e se cercate di prevedere cosa succeder\u00e0 a quel bruco, alla fine finir\u00e0 di mangiare la foglia e morir\u00e0. Ma succede qualcosa, una crisalide, e il bruco finisce per diventare una farfalla. Questa farfalla impolliner\u00e0 i fiori intorno a s\u00e9 e diventer\u00e0 una forza di bont\u00e0, gentilezza e cura.<br \/>\nTuttavia, questo processo di cristallizzazione non \u00e8 facile. Il sistema immunitario del bruco attacca la farfalla e ho sentito che questo \u00e8 qualcosa che sta accadendo all&#8217;umanit\u00e0 da qualche tempo. Potremmo dire che alcune di quelle prime cellule, attaccate erano Martin Luther King, Gandhi, JFK, suo fratello Robert, Abraham Lincoln. Anche nei nostri miti, Ges\u00f9, Socrate, Buddha sono stati uccisi.<br \/>\nTuttavia, stiamo raggiungendo un punto, dal mio punto di vista, dalla mia prospettiva, dove vedo un po&#8217; di luce.<br \/>\nOra, il problema che ho sempre \u00e8 che \u00e8 difficile e richiede trasformazioni personali per ognuno di noi e una pi\u00f9 ampia cultura di compassione, empatia e razionalit\u00e0.<br \/>\nDiciamo che siamo riusciti a creare forti movimenti sociali attraverso l&#8217;auto-organizzazione. A chi chiediamo il cambiamento?<br \/>\nGli stati nazionali potrebbero non avere tutto il potere che sembrano avere, perch\u00e9 dietro di loro c&#8217;\u00e8 un&#8217;\u00e9lite globale di corporazioni pi\u00f9 ricche interconnesse in tutto il mondo. Non c&#8217;\u00e8 un governo mondiale che abbia la capacit\u00e0 di decidere queste questioni. Ci sono le Nazioni Unite, ma non hanno alcun potere alle spalle. Anche se riusciamo a modificare la Dichiarazione Universale dei Diritti Umani, chi garantir\u00e0 che questi diritti universali siano rispettati? Pu\u00f2 commentare questa domanda?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b10c6 elementor-widget elementor-widget-heading\" data-id=\"b0b10c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Roberto:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e1b61e elementor-widget elementor-widget-text-editor\" data-id=\"7e1b61e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Penso che ci siano due questioni totalmente diverse. La questione della farfalla mi serve per essere ottimista sul futuro perch\u00e9 la storia dell&#8217;umanit\u00e0 mostra chiaramente che l&#8217;umanit\u00e0 sta progredendo. Non \u00e8 un progresso lineare, ma fondamentalmente sta progredendo. Voglio dire che oggi abbiamo cose come una biblioteca e un sistema sonar, e in questa societ\u00e0 oggi un lavoratore vive molto meglio dell&#8217;aristocratico del 1800. \u00c8 pi\u00f9 sicuro nel suo futuro, l&#8217;aristocratico dipendeva molto dalla guerra, dalle lotte feudali. Oggi un operaio \u00e8 molto pi\u00f9 sicuro.<\/p>\n<p>Ma il mio problema \u00e8 diverso.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8fff6b elementor-widget elementor-widget-heading\" data-id=\"e8fff6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parte 3. La crisi del diritto internazionale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b8e3464 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8e3464\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-312174c\" data-id=\"312174c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6eb76f elementor-widget elementor-widget-video\" data-id=\"f6eb76f\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/NNx4iQCjn3A&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ad65a9\" data-id=\"8ad65a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0333f4f elementor-widget elementor-widget-text-editor\" data-id=\"0333f4f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roberto esprime le sue opinioni sul problema delle Nazioni Unite che non hanno potere decisionale sulle relazioni internazionali e descrive la crisi del diritto internazionale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2e3ec5 elementor-blockquote--skin-quotation elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"a2e3ec5\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t<p>Siamo usciti con l'idea che il diritto internazionale fosse uno strumento per regolare le relazioni internazionali. E su questo concetto abbiamo costruito le Nazioni Unite, e abbiamo creato una serie di strumenti tutti basati sul diritto internazionale. Oggi il diritto internazionale non \u00e8 pi\u00f9 uno strumento indiscusso delle relazioni internazionali. Al contrario.<\/p>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Roberto Savio<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-88fcf0e elementor-blockquote--skin-quotation elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"88fcf0e\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t<p>Quindi abbiamo una chiara crisi del diritto internazionale e del concetto, che i paesi hanno diritti, che i paesi fanno parte di un consenso di voto. Penso che questo sia il vero problema che abbiamo. E non possiamo avere una governance globale se non accettiamo certi valori globali, certi valori comuni, e abbiamo perso questi valori comuni.<br \/>\nOggi, c'\u00e8 una frammentazione dei valori secondo gli interessi locali, e l'uso di politici brillanti per andare al potere e rimanere al potere. E credo che questo sia un problema molto, molto serio per la democrazia, e quello che mi preoccupa, credo, \u00e8 che se i giovani si mobilitano contro questo, non struttureranno una formula di confronto che sia dello stesso livello di rappresentativit\u00e0 e forza (della loro opposizione).<\/p>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Roberto Savio<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-727a4fa elementor-widget elementor-widget-toggle\" data-id=\"727a4fa\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1201\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1201\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Leggi la trascrizione completa<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1201\"><p>Il mio problema \u00e8 che il mondo \u00e8 organizzato per Nazioni.<\/p>\n<p>Ora supponiamo che mentre stiamo parlando, tu ed io, qualcuno atterri da un pianeta e ci dica:<\/p>\n<p>&#8211; &#8220;Cosa state facendo?&#8221;<\/p>\n<p>&#8211; &#8220;Ci stiamo scambiando opinioni&#8221;.<\/p>\n<p>&#8211; &#8220;Punti di vista su cosa?<\/p>\n<p>&#8211; &#8220;Sulla governance&#8221;.<\/p>\n<p>&#8211; &#8220;Cos&#8217;\u00e8 la governance?&#8221;<\/p>\n<p>&#8211; &#8220;Beh, la governance \u00e8 il sistema attraverso il quale mettete in relazione le societ\u00e0, possibilmente, per i migliori miglioramenti delle societ\u00e0&#8221;.<\/p>\n<p>&#8211; &#8220;Perch\u00e9, avete delle societ\u00e0?&#8221;.<\/p>\n<p>&#8211; &#8220;S\u00ec, certo, e ora sono organizzate in nazioni&#8221;.<\/p>\n<p>&#8211; &#8220;E cos&#8217;\u00e8 una nazione?&#8221;.<\/p>\n<p>&#8211; &#8220;Una nazione \u00e8 uno spazio occupato da persone con entit\u00e0 comuni, o una storia comune, cose che le rendono distinte dalle altre persone, \u00e8 la migliore informazione&#8221;.<br \/>\n&#8211; &#8220;Ah, e come sono organizzate queste nazioni?&#8221;.<\/p>\n<p>&#8211; &#8220;Le Nazioni Unite sono state messe insieme alla fine della seconda guerra mondiale per evitare il ripetersi di una guerra mondiale, per cui avete un consiglio di sicurezza, che si occupa della sicurezza delle nazioni&#8221;.<\/p>\n<p>&#8211; &#8220;Ahh, molto interessante, come funziona?&#8221;.<\/p>\n<p>&#8211; &#8220;Beh, ci sono 15 paesi, cinque sono permanenti, perch\u00e9 sono stati i vincitori della guerra mondiale, e gli altri vengono eletti ogni anno&#8221;.<\/p>\n<p>&#8211; &#8220;Ah, e perch\u00e9, cos&#8217;\u00e8 la pace?&#8221;.<\/p>\n<p>&#8211; &#8220;La pace \u00e8 che non possiamo farci la guerra tra di noi&#8221;.<\/p>\n<p>&#8211; &#8220;Cos&#8217;\u00e8 la guerra?&#8221;<\/p>\n<p>&#8211; &#8220;La guerra \u00e8 l&#8217;uso della forza con una tecnologia adeguata, oltre alla natura umana, per vincere la diversit\u00e0&#8221;.<\/p>\n<p>&#8211; &#8220;Ah, quindi voi fate la guerra con una tecnologia adeguata, le armi?&#8221;.<\/p>\n<p>&#8211; &#8220;S\u00ec e da dove vengono queste armi?&#8221;.<\/p>\n<p>&#8211; &#8220;Beh, l&#8217;88 viene dai cinque membri permanenti del consiglio di sicurezza&#8221;.<\/p>\n<p>Il tizio che veniva dal pianeta volava indietro dicendo che questa \u00e8 una societ\u00e0 che non ha senso.<\/p>\n<p>Le Nazioni Unite sono state lentamente private di qualsiasi strumento di potere perch\u00e9 lo hanno fatto le grandi potenze. I due strumenti di relazione globale, la finanza e il commercio. Il commercio, hanno tolto il commercio dalle Nazioni Unite creando l&#8217;Organizzazione del Commercio Mondiale, che non fa parte delle Nazioni Unite. La finanza non \u00e8 mai stata nelle Nazioni Unite perch\u00e9 all&#8217;inizio era un sistema diverso, chiamato Bretton Woods, e nessuna delle istituzioni di quel sistema ha alcun potere sulla globalizzazione.<\/p>\n<p>La finanza \u00e8 totalmente non regolamentata. \u00c8 l&#8217;unico settore dell&#8217;attivit\u00e0 umana senza alcuna regolamentazione. Quindi questa finanza, ormai globalizzata, non \u00e8 pi\u00f9 il grasso del sistema economico. \u00c8 uscita, ha una vita propria, non ci sono regole. Crea un casin\u00f2, dove ora l&#8217;acqua \u00e8 quotata in borsa. Mi chiedo quando l&#8217;aria sar\u00e0 quotata in borsa.<\/p>\n<p>I brevetti sulla vita, come i vaccini, ti dimostrano che stiamo dando alla finanza, e al profitto, anche la vita, che non \u00e8 un affare minore. Non era cos\u00ec 40, 50 anni fa.<\/p>\n<p>E, in tutto questo casin\u00f2 senza regole, la finanza riesce a controllare i paesi. Il bilancio della finanza \u00e8 molte volte superiore al bilancio dei paesi. Oggi per ogni dollaro di commercio, di cose che sono state fatte dagli uomini, sia servizi che beni, ci sono 40 dollari di transazioni della finanza. Quindi la transazione della finanza \u00e8 40 dollari pi\u00f9 grande dell&#8217;economia reale.<\/p>\n<p>Ed \u00e8 totalmente delicata dalla vostra economia. La borsa va senza alcuna relazione con la realt\u00e0 economica. Al tempo della grande crisi della pandemia, la borsa \u00e8 salita. E abbiamo tanti esempi di questo.<\/p>\n<p>Quindi il mio punto \u00e8 che il diritto internazionale \u00e8 quello che \u00e8 in crisi. Siamo usciti con l&#8217;idea che il diritto internazionale fosse uno strumento per regolare le relazioni internazionali. E su questo concetto abbiamo costruito le Nazioni Unite, e abbiamo creato una serie di strumenti tutti basati sul diritto internazionale. Oggi il diritto internazionale non \u00e8 pi\u00f9 uno strumento indiscusso delle relazioni internazionali. Al contrario. Ci sono paesi che non accettano nemmeno il diritto internazionale. Dicono che \u00e8 uno strumento occidentale, a partire da Erdogan a Bolsonaro, o Orban. Orban, con rabbia, ha detto che crede in una democrazia liberale. \u00c8 stato espulso dal Partito Popolare e ora sta mettendo in piedi una destra estrema, che non riconosce il diritto internazionale.<\/p>\n<p>C&#8217;\u00e8 un accordo sulla migrazione, &#8220;non ci interessa&#8221;; c&#8217;\u00e8 un accordo sui diritti delle donne &#8220;non ci interessa&#8221;; c&#8217;\u00e8 un accordo su lgbtq &#8220;non ci interessa&#8221;. E cos\u00ec \u00e8 l&#8217;idea di diritto internazionale che \u00e8 in crisi. La Dichiarazione dei diritti umani potrebbe essere firmata oggi? Le Nazioni Unite potrebbero essere create oggi? Impossibile. Con Trump non c&#8217;\u00e8 assolutamente modo. Ora Putin non creerebbe una Nazione Unita. XI creerebbe una Nazione Unita? Ne dubito. Sarebbe un&#8217;altra nazione unita, sarebbe una specie di&#8230;<\/p>\n<p>Non dimenticate che il G6, il G7, il G20 sono stati tutti creati per togliere alle Nazioni Unite il posto di discussione e decisione. Quindi abbiamo una chiara crisi del diritto internazionale e del concetto, che i paesi hanno diritti, che i paesi fanno parte di un consenso di voto, e cos\u00ec via. E penso che questo sia il vero problema che abbiamo. E non possiamo avere una governance globale se non accettiamo alcuni valori globali, alcuni valori comuni, e abbiamo perso questi valori comuni.<\/p>\n<p>Questi valori comuni non ci sono pi\u00f9. Oggi c&#8217;\u00e8 una frammentazione dei valori secondo gli interessi locali, e l&#8217;uso di politici brillanti per usare il popolo per arrivare al potere e rimanere al potere. E penso che questo sia un problema molto, molto serio per la democrazia. E quello che mi preoccupa, credo, \u00e8 che mentre i giovani si mobilitano contro questo, non strutturano una formula di confronto che sia dello stesso livello di rappresentativit\u00e0 e forza.<\/p>\n<p>Questo \u00e8 il mio problema. Spero che si possa, spero che arrivi, ma purtroppo non \u00e8 cos\u00ec. Guardate il grande movimento di Black Lives Matter, ha mosso milioni di persone, Me Too ha mosso milioni di milioni di persone, ma devono cercare qualche rappresentante nei parlamenti, nel congresso, che li ascoltino e diventino loro portavoce, ma non sono mai stati eletti portavoce. L&#8217;hanno fatto perch\u00e9 o pochi hanno creduto nella questione, o la maggioranza, in modo che ci sia un modo per ottenere pi\u00f9 voti.<\/p>\n<p>sono pi\u00f9. Oggi<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f026777 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f026777\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4d7eda\" data-id=\"b4d7eda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6df1e05 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6df1e05\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/youtu.be\/84PEtH5WF-Y\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Guarda la conversazione completa su YouTube<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-530e2dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"530e2dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-edd30dc\" data-id=\"edd30dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f94e648 elementor-share-buttons--shape-rounded elementor-share-buttons--align-center elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"f94e648\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Condividi su facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Condividi su twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Condividi su linkedin\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_email\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Condividi su email\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-421cc03 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"421cc03\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-851d5cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"851d5cb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6807e8c\" data-id=\"6807e8c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34f3cdb elementor-widget elementor-widget-facebook-comments\" data-id=\"34f3cdb\" data-element_type=\"widget\" data-widget_type=\"facebook-comments.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-facebook-widget fb-comments\" data-href=\"https:\/\/sorinionescu.org\/it\/?p=840\" data-width=\"100%\" data-numposts=\"10\" data-order-by=\"social\" style=\"min-height: 1px\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Roberto Savio\u00a0\u00e8 giornalista, esperto di comunicazione, commentatore politico, attivista per la giustizia sociale e climatica e avvocato della governance globale. \u00c8 fondatore e presidente emerito dell\u2019agenzia di stampa\u00a0Inter Press Service (IPS)\u00a0ed editore di Other News. Ho avuto la fortuna di incontrare Roberto attraverso il mio attivismo, e quando ho iniziato a interessarmi la governance globale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,32],"tags":[],"class_list":["post-840","post","type-post","status-publish","format-standard","hentry","category-articles","category-articles-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu\" \/>\n<meta property=\"og:description\" content=\"Roberto Savio\u00a0\u00e8 giornalista, esperto di comunicazione, commentatore politico, attivista per la giustizia sociale e climatica e avvocato della governance globale. \u00c8 fondatore e presidente emerito dell\u2019agenzia di stampa\u00a0Inter Press Service (IPS)\u00a0ed editore di Other News. Ho avuto la fortuna di incontrare Roberto attraverso il mio attivismo, e quando ho iniziato a interessarmi la governance globale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorin Ionescu\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-10T11:12:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-10T11:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\" \/>\n<meta name=\"author\" content=\"Sorin Ionescu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorin Ionescu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/\"},\"author\":{\"name\":\"Sorin Ionescu\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"headline\":\"Governance globale e movimenti sociali &#8211; dialogo con Roberto Savio\",\"datePublished\":\"2021-04-10T11:12:30+00:00\",\"dateModified\":\"2021-04-10T11:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/\"},\"wordCount\":3752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"articleSection\":[\"Articles\",\"Articles\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/\",\"name\":\"Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"datePublished\":\"2021-04-10T11:12:30+00:00\",\"dateModified\":\"2021-04-10T11:28:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/articles-it\\\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sorinionescu.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governance globale e movimenti sociali &#8211; dialogo con Roberto Savio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#website\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/\",\"name\":\"Sorin Ionescu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sorinionescu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/#\\\/schema\\\/person\\\/8b60c7d9c1322e6c108e45a89abb67ae\",\"name\":\"Sorin Ionescu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"url\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"contentUrl\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\",\"width\":126,\"height\":119,\"caption\":\"Sorin Ionescu\"},\"logo\":{\"@id\":\"https:\\\/\\\/sorinionescu.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/cropped-SorinLogo.png\"},\"sameAs\":[\"https:\\\/\\\/sorinionescu.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/","og_locale":"it_IT","og_type":"article","og_title":"Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu","og_description":"Roberto Savio\u00a0\u00e8 giornalista, esperto di comunicazione, commentatore politico, attivista per la giustizia sociale e climatica e avvocato della governance globale. \u00c8 fondatore e presidente emerito dell\u2019agenzia di stampa\u00a0Inter Press Service (IPS)\u00a0ed editore di Other News. Ho avuto la fortuna di incontrare Roberto attraverso il mio attivismo, e quando ho iniziato a interessarmi la governance globale [&hellip;]","og_url":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/","og_site_name":"Sorin Ionescu","article_published_time":"2021-04-10T11:12:30+00:00","article_modified_time":"2021-04-10T11:28:42+00:00","og_image":[{"url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","type":"","width":"","height":""}],"author":"Sorin Ionescu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sorin Ionescu","Tempo di lettura stimato":"19 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#article","isPartOf":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/"},"author":{"name":"Sorin Ionescu","@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"headline":"Governance globale e movimenti sociali &#8211; dialogo con Roberto Savio","datePublished":"2021-04-10T11:12:30+00:00","dateModified":"2021-04-10T11:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/"},"wordCount":3752,"commentCount":0,"publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"image":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","articleSection":["Articles","Articles"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/","url":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/","name":"Governance globale e movimenti sociali - dialogo con Roberto Savio ~ Sorin Ionescu","isPartOf":{"@id":"https:\/\/sorinionescu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#primaryimage"},"image":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#primaryimage"},"thumbnailUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","datePublished":"2021-04-10T11:12:30+00:00","dateModified":"2021-04-10T11:28:42+00:00","breadcrumb":{"@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#primaryimage","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2020\/12\/journalist-communication-expert-political-commentator-activist-for-social-and-climate-justice-advocate-of-global-governance..png"},{"@type":"BreadcrumbList","@id":"https:\/\/sorinionescu.org\/it\/articles-it\/governance-globale-e-movimenti-sociali-dialogo-con-roberto-savio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sorinionescu.org\/it\/"},{"@type":"ListItem","position":2,"name":"Governance globale e movimenti sociali &#8211; dialogo con Roberto Savio"}]},{"@type":"WebSite","@id":"https:\/\/sorinionescu.org\/#website","url":"https:\/\/sorinionescu.org\/","name":"Sorin Ionescu","description":"","publisher":{"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sorinionescu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/sorinionescu.org\/#\/schema\/person\/8b60c7d9c1322e6c108e45a89abb67ae","name":"Sorin Ionescu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","url":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","contentUrl":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png","width":126,"height":119,"caption":"Sorin Ionescu"},"logo":{"@id":"https:\/\/sorinionescu.org\/wp-content\/uploads\/2019\/08\/cropped-SorinLogo.png"},"sameAs":["https:\/\/sorinionescu.org"]}]}},"_links":{"self":[{"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/posts\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":2,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/posts\/840\/revisions"}],"predecessor-version":[{"id":848,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/posts\/840\/revisions\/848"}],"wp:attachment":[{"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/media?parent=840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/categories?post=840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sorinionescu.org\/it\/wp-json\/wp\/v2\/tags?post=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}